
{"id":3824,"date":"2014-12-03T09:12:19","date_gmt":"2014-12-03T11:12:19","guid":{"rendered":"https:\/\/siteshom.goias.gov.br\/agehab\/aviso-adiamento-sine-die-do-pregao-eletronico-no-018-2014\/"},"modified":"2014-12-03T09:12:19","modified_gmt":"2014-12-03T11:12:19","slug":"aviso-adiamento-sine-die-do-pregao-eletronico-no-018-2014","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/agehab\/aviso-adiamento-sine-die-do-pregao-eletronico-no-018-2014\/","title":{"rendered":"AVISO ADIAMENTO SINE-DIE DO PREGAO ELETRONICO N\u00ba 018\/2014"},"content":{"rendered":"<p><!DOCTYPE html PUBLIC \"-\/\/W3C\/\/DTD HTML 4.0 Transitional\/\/EN\" \"http:\/\/www.w3.org\/TR\/REC-html40\/loose.dtd\"><br \/>\n<html><body><\/p>\n<p align=\"center\"><strong>AVISO DE ADIAMENTO &ldquo;SINE-DIE&rdquo;<\/strong><\/p>\n<p align=\"center\"><strong>PREG&Atilde;O ELETR&Ocirc;NICO N&ordm; 018\/2014<\/strong><\/p>\n<p><strong>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; <\/strong><\/p>\n<p><strong>A AG&Ecirc;NCIA GOIANA DE HABITA&Ccedil;&Atilde;O S\/A &ndash; AGEHAB<\/strong>, por interm&eacute;dio de seu Pregoeiro, torna p&uacute;blico aos interessados que fica <strong><span style=\"text-decoration: underline;\">ADIADO<\/span><\/strong> <strong>&ldquo;<em>SINE DIE&rdquo;<\/em><\/strong> o Preg&atilde;o Eletr&ocirc;nico n&ordm; 018\/2014 em fun&ccedil;&atilde;o de apresenta&ccedil;&atilde;o de impugna&ccedil;&atilde;o ao edital. Esclarecimentos e d&uacute;vidas poder&atilde;o ser dirimidas ao Pregoeiro na sede da AGEHAB, em hor&aacute;rio de expediente das 08h00 &agrave;s 12h00 e das 14h00 &agrave;s 18h00, pelo fone (62) 3096-5041.<\/p>\n<p>Goi&acirc;nia, 03 de dezembro de 2014.<\/p>\n<p align=\"center\"><strong>Aquilino Alves de Macedo<\/strong><\/p>\n<p align=\"center\"><strong>Pregoeiro<\/strong><\/p>\n<p><\/body><\/html><\/p>\n","protected":false},"excerpt":{"rendered":"<p>AVISO DE ADIAMENTO &ldquo;SINE-DIE&rdquo; PREG&Atilde;O ELETR&Ocirc;NICO N&ordm; 018\/2014 &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; A AG&Ecirc;NCIA GOIANA DE HABITA&Ccedil;&Atilde;O S\/A &ndash; AGEHAB, por interm&eacute;dio de seu Pregoeiro, torna p&uacute;blico aos interessados que fica ADIADO &ldquo;SINE DIE&rdquo; o Preg&atilde;o Eletr&ocirc;nico n&ordm; 018\/2014 em fun&ccedil;&atilde;o de apresenta&ccedil;&atilde;o de impugna&ccedil;&atilde;o ao edital. Esclarecimentos e d&uacute;vidas poder&atilde;o ser dirimidas ao Pregoeiro na sede da [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-3824","post","type-post","status-publish","format-standard","hentry","category-pregoes-eletronicos-2014"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"gustavogoncalves","author_link":"https:\/\/goias.gov.br\/agehab\/author\/gustavogoncalves\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/agehab\/category\/licitacoes-e-contratacoes\/pregoes-eletronicos-2014\/\" rel=\"category tag\">Preg\u00f5es Eletr\u00f4nicos 2014<\/a>","rttpg_excerpt":"AVISO DE ADIAMENTO &ldquo;SINE-DIE&rdquo; PREG&Atilde;O ELETR&Ocirc;NICO N&ordm; 018\/2014 &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; A AG&Ecirc;NCIA GOIANA DE HABITA&Ccedil;&Atilde;O S\/A &ndash; AGEHAB, por interm&eacute;dio de seu Pregoeiro, torna p&uacute;blico aos interessados que fica ADIADO &ldquo;SINE DIE&rdquo; o Preg&atilde;o Eletr&ocirc;nico n&ordm; 018\/2014 em fun&ccedil;&atilde;o de apresenta&ccedil;&atilde;o de impugna&ccedil;&atilde;o ao edital. Esclarecimentos e d&uacute;vidas poder&atilde;o ser dirimidas ao Pregoeiro na sede da&hellip;","_links":{"self":[{"href":"https:\/\/goias.gov.br\/agehab\/wp-json\/wp\/v2\/posts\/3824","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/agehab\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/agehab\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/agehab\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/agehab\/wp-json\/wp\/v2\/comments?post=3824"}],"version-history":[{"count":0,"href":"https:\/\/goias.gov.br\/agehab\/wp-json\/wp\/v2\/posts\/3824\/revisions"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/agehab\/wp-json\/wp\/v2\/media?parent=3824"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/agehab\/wp-json\/wp\/v2\/categories?post=3824"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/agehab\/wp-json\/wp\/v2\/tags?post=3824"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}