{"id":9457,"date":"2020-03-16T12:00:32","date_gmt":"2020-03-16T15:00:32","guid":{"rendered":"http:\/\/localhost\/multisites\/sead\/2020\/03\/16\/escola-de-governo-suspende-oficina-para-estagiarios\/"},"modified":"2023-10-18T15:36:01","modified_gmt":"2023-10-18T18:36:01","slug":"escola-de-governo-suspende-oficina-para-estagiarios","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/administracao\/escola-de-governo-suspende-oficina-para-estagiarios\/","title":{"rendered":"Escola de Governo suspende oficina para estagi\u00e1rios"},"content":{"rendered":"<p>A Escola de Governo informa que a oficina de integra&ccedil;&atilde;o que comp&otilde;e uma das etapas do processo seletivo para estagi&aacute;rios, conforme Edital n. 006\/2019 Sead, programada para amanh&atilde;, dia 17\/03, est&aacute; cancelada.<\/p>\n<p>Ser&aacute; agendada e informada nova data oportunamente.<\/p>\n<p><strong>Secretaria de Estado da Administra&ccedil;&atilde;o<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Escola de Governo informa que a oficina de integra&ccedil;&atilde;o que comp&otilde;e uma das etapas do processo seletivo para estagi&aacute;rios, conforme Edital n. 006\/2019 Sead, programada para amanh&atilde;, dia 17\/03, est&aacute; cancelada. Ser&aacute; agendada e informada nova data oportunamente. Secretaria de Estado da Administra&ccedil;&atilde;o<\/p>\n","protected":false},"author":57,"featured_media":9456,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[121],"tags":[],"class_list":["post-9457","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-novas"],"rttpg_featured_image_url":{"full":["https:\/\/goias.gov.br\/administracao\/wp-content\/uploads\/sites\/27\/2020\/03\/20200316-oficina_de_estagirios_cancelada-6fd.jpg",961,541,false],"landscape":["https:\/\/goias.gov.br\/administracao\/wp-content\/uploads\/sites\/27\/2020\/03\/20200316-oficina_de_estagirios_cancelada-6fd.jpg",961,541,false],"portraits":["https:\/\/goias.gov.br\/administracao\/wp-content\/uploads\/sites\/27\/2020\/03\/20200316-oficina_de_estagirios_cancelada-6fd.jpg",961,541,false],"thumbnail":["https:\/\/goias.gov.br\/administracao\/wp-content\/uploads\/sites\/27\/2020\/03\/20200316-oficina_de_estagirios_cancelada-6fd-150x150.jpg",150,150,true],"medium":["https:\/\/goias.gov.br\/administracao\/wp-content\/uploads\/sites\/27\/2020\/03\/20200316-oficina_de_estagirios_cancelada-6fd-300x169.jpg",300,169,true],"large":["https:\/\/goias.gov.br\/administracao\/wp-content\/uploads\/sites\/27\/2020\/03\/20200316-oficina_de_estagirios_cancelada-6fd.jpg",961,541,false],"1536x1536":["https:\/\/goias.gov.br\/administracao\/wp-content\/uploads\/sites\/27\/2020\/03\/20200316-oficina_de_estagirios_cancelada-6fd.jpg",961,541,false],"2048x2048":["https:\/\/goias.gov.br\/administracao\/wp-content\/uploads\/sites\/27\/2020\/03\/20200316-oficina_de_estagirios_cancelada-6fd.jpg",961,541,false]},"rttpg_author":{"display_name":"vaniamc","author_link":"https:\/\/goias.gov.br\/administracao\/author\/vaniamc\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/administracao\/categoria\/noticias-novas\/\" rel=\"category tag\">Not\u00edcias<\/a>","rttpg_excerpt":"A Escola de Governo informa que a oficina de integra&ccedil;&atilde;o que comp&otilde;e uma das etapas do processo seletivo para estagi&aacute;rios, conforme Edital n. 006\/2019 Sead, programada para amanh&atilde;, dia 17\/03, est&aacute; cancelada. Ser&aacute; agendada e informada nova data oportunamente. Secretaria de Estado da Administra&ccedil;&atilde;o","_links":{"self":[{"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/posts\/9457","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/users\/57"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/comments?post=9457"}],"version-history":[{"count":1,"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/posts\/9457\/revisions"}],"predecessor-version":[{"id":15911,"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/posts\/9457\/revisions\/15911"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/media\/9456"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/media?parent=9457"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/categories?post=9457"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/tags?post=9457"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}