{"id":5014,"date":"2019-08-01T10:26:59","date_gmt":"2019-08-01T13:26:59","guid":{"rendered":"http:\/\/localhost\/multisites\/sead\/2019\/08\/01\/sead-realiza-mais-uma-etapa-do-programa-de-transformacao-da-gestao-na-dgap-3\/"},"modified":"2023-10-18T15:36:34","modified_gmt":"2023-10-18T18:36:34","slug":"sead-realiza-mais-uma-etapa-do-programa-de-transformacao-da-gestao-na-dgap-3","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/administracao\/sead-realiza-mais-uma-etapa-do-programa-de-transformacao-da-gestao-na-dgap-3\/","title":{"rendered":"SEAD realiza mais uma etapa do Programa de Transforma\u00e7\u00e3o da Gest\u00e3o na DGAP"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-5013\" src=\"https:\/\/goias.gov.br\/administracao\/wp-content\/uploads\/sites\/27\/2019\/08\/01-08-DGAP-1-060.jpeg\" alt=\"\" width=\"1280\" height=\"622\" srcset=\"https:\/\/goias.gov.br\/administracao\/wp-content\/uploads\/sites\/27\/2019\/08\/01-08-DGAP-1-060.jpeg 1280w, https:\/\/goias.gov.br\/administracao\/wp-content\/uploads\/sites\/27\/2019\/08\/01-08-DGAP-1-060-300x146.jpeg 300w, https:\/\/goias.gov.br\/administracao\/wp-content\/uploads\/sites\/27\/2019\/08\/01-08-DGAP-1-060-1024x498.jpeg 1024w, https:\/\/goias.gov.br\/administracao\/wp-content\/uploads\/sites\/27\/2019\/08\/01-08-DGAP-1-060-768x373.jpeg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/p>\n<p>O Governo de Goi&aacute;s, por meio da Secretaria de Estado da Administra&ccedil;&atilde;o &ndash; SEAD, iniciou na manh&atilde; da &uacute;ltima quarta-feira, 31, a Constru&ccedil;&atilde;o da Cadeia de Valor do Programa de Transforma&ccedil;&atilde;o da Gest&atilde;o na Diretoria Geral de Administra&ccedil;&atilde;o Penitenci&aacute;ria (<span rel=\"DGAP\">DGAP<\/span>). O semin&aacute;rio ocorreu na Escola Superior de Administra&ccedil;&atilde;o Penitenci&aacute;ria e marca mais uma etapa para a implanta&ccedil;&atilde;o do Projeto, pactuado em junho entre o&nbsp;titular da SEAD, Pedro Sales e o Diretor Geral da DGAP, Coronel Urz&ecirc;da.<\/p>\n<p>O intuito do projeto &eacute; ampliar a capacidade de entrega de servi&ccedil;os de qualidade ao cidad&atilde;o. Uma das principais vertentes para alcan&ccedil;ar a transforma&ccedil;&atilde;o desejada, est&aacute; vinculada a uma arquitetura organizacional que dialogue com a estrat&eacute;gia e conte com servidores engajados e com boa vontade. O processo de Constru&ccedil;&atilde;o da Cadeia de Valor apresenta aos colaboradores uma vis&atilde;o sist&ecirc;mica de todos os processos organizacionais da DGAP que, se executados integralmente, criar&atilde;o um ambiente interno capaz de coordenar e orientar a institui&ccedil;&atilde;o para uma atua&ccedil;&atilde;o que fa&ccedil;a com que o cidad&atilde;o perceba e sinta a atua&ccedil;&atilde;o do governo.<\/p>\n<p>Esse instrumento de gest&atilde;o que integra o Estado como um ente &uacute;nico e respons&aacute;vel por entregar valor ao cidad&atilde;o, promove ainda mudan&ccedil;as de <em>mindset<\/em> nas equipes envolvidas, por meio da sensibiliza&ccedil;&atilde;o, do engajamento e da prepara&ccedil;&atilde;o dos servidores para a constru&ccedil;&atilde;o de uma nova cultura organizacional, propiciando que os colaboradores sejam protagonistas no processo de transforma&ccedil;&atilde;o e inova&ccedil;&atilde;o institucional.<\/p>\n<p>A equipe da Subsecretaria de Administra&ccedil;&atilde;o e Desburocratiza&ccedil;&atilde;o \/ Superintend&ecirc;ncia Central de Transforma&ccedil;&atilde;o da Gest&atilde;o P&uacute;blica realizou a &ldquo;Oficina de Entendimento do Modelo de Neg&oacute;cio da DGAP&rdquo;. O conte&uacute;do visa o alinhamento do entendimento da Alta Dire&ccedil;&atilde;o da DGAP em rela&ccedil;&atilde;o ao Modelo de Neg&oacute;cio da institui&ccedil;&atilde;o, permitindo aos participantes entenderem a organiza&ccedil;&atilde;o como um conjunto de partes que colaboram entre si para entregar valor ao cidad&atilde;o.<\/p>\n<p>A etapa seguinte identificar&aacute; os principais processos organizacionais, dando desdobramento na Arquitetura de Processos da DGAP. A Jornada de Transforma&ccedil;&atilde;o dos Servi&ccedil;os P&uacute;blicos possui 5 passos fundamentais:<\/p>\n<ol>\n<li>Cria&ccedil;&atilde;o da Rede de Transforma&ccedil;&atilde;o<\/li>\n<li>Elabora&ccedil;&atilde;o dos Regulamentos<\/li>\n<li>Constru&ccedil;&atilde;o da Carta de Servi&ccedil;os do Estado de Goi&aacute;s<\/li>\n<li>Constru&ccedil;&atilde;o da Cadeia de Valor<\/li>\n<li>Transforma&ccedil;&atilde;o dos Servi&ccedil;os<\/li>\n<\/ol>\n<p>Comunica&ccedil;&atilde;o Setorial SEAD<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Governo de Goi&aacute;s, por meio da Secretaria de Estado da Administra&ccedil;&atilde;o &ndash; SEAD, iniciou na manh&atilde; da &uacute;ltima quarta-feira, 31, a Constru&ccedil;&atilde;o da Cadeia de Valor do Programa de Transforma&ccedil;&atilde;o da Gest&atilde;o na Diretoria Geral de Administra&ccedil;&atilde;o Penitenci&aacute;ria (DGAP). O semin&aacute;rio ocorreu na Escola Superior de Administra&ccedil;&atilde;o Penitenci&aacute;ria e marca mais uma etapa para [&hellip;]<\/p>\n","protected":false},"author":51,"featured_media":5010,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[121],"tags":[],"class_list":["post-5014","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-novas"],"rttpg_featured_image_url":{"full":["https:\/\/goias.gov.br\/administracao\/wp-content\/uploads\/sites\/27\/2019\/08\/01-08-DGAP-2-809.jpeg",1280,622,false],"landscape":["https:\/\/goias.gov.br\/administracao\/wp-content\/uploads\/sites\/27\/2019\/08\/01-08-DGAP-2-809.jpeg",1280,622,false],"portraits":["https:\/\/goias.gov.br\/administracao\/wp-content\/uploads\/sites\/27\/2019\/08\/01-08-DGAP-2-809.jpeg",1280,622,false],"thumbnail":["https:\/\/goias.gov.br\/administracao\/wp-content\/uploads\/sites\/27\/2019\/08\/01-08-DGAP-2-809-150x150.jpeg",150,150,true],"medium":["https:\/\/goias.gov.br\/administracao\/wp-content\/uploads\/sites\/27\/2019\/08\/01-08-DGAP-2-809-300x146.jpeg",300,146,true],"large":["https:\/\/goias.gov.br\/administracao\/wp-content\/uploads\/sites\/27\/2019\/08\/01-08-DGAP-2-809-1024x498.jpeg",1024,498,true],"1536x1536":["https:\/\/goias.gov.br\/administracao\/wp-content\/uploads\/sites\/27\/2019\/08\/01-08-DGAP-2-809.jpeg",1280,622,false],"2048x2048":["https:\/\/goias.gov.br\/administracao\/wp-content\/uploads\/sites\/27\/2019\/08\/01-08-DGAP-2-809.jpeg",1280,622,false]},"rttpg_author":{"display_name":"petrasdavid","author_link":"https:\/\/goias.gov.br\/administracao\/author\/petrasdavid\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/administracao\/categoria\/noticias-novas\/\" rel=\"category tag\">Not\u00edcias<\/a>","rttpg_excerpt":"O Governo de Goi&aacute;s, por meio da Secretaria de Estado da Administra&ccedil;&atilde;o &ndash; SEAD, iniciou na manh&atilde; da &uacute;ltima quarta-feira, 31, a Constru&ccedil;&atilde;o da Cadeia de Valor do Programa de Transforma&ccedil;&atilde;o da Gest&atilde;o na Diretoria Geral de Administra&ccedil;&atilde;o Penitenci&aacute;ria (DGAP). O semin&aacute;rio ocorreu na Escola Superior de Administra&ccedil;&atilde;o Penitenci&aacute;ria e marca mais uma etapa para&hellip;","_links":{"self":[{"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/posts\/5014","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/users\/51"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/comments?post=5014"}],"version-history":[{"count":1,"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/posts\/5014\/revisions"}],"predecessor-version":[{"id":16158,"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/posts\/5014\/revisions\/16158"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/media\/5010"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/media?parent=5014"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/categories?post=5014"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/tags?post=5014"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}