{"id":2600,"date":"2014-01-15T09:01:28","date_gmt":"2014-01-15T11:01:28","guid":{"rendered":"http:\/\/localhost\/multisites\/sead\/2014\/01\/15\/sectec-legislacao-2013\/"},"modified":"2023-10-18T16:26:11","modified_gmt":"2023-10-18T19:26:11","slug":"sectec-legislacao-2013","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/administracao\/sectec-legislacao-2013\/","title":{"rendered":"SECTEC &#8211; Legisla\u00e7\u00e3o 2013"},"content":{"rendered":"<table style=\"width: 100%;\" border=\"1\" cellspacing=\"1\" cellpadding=\"1\">\n<tbody>\n<tr>\n<td colspan=\"8\" align=\"right\"><a href=\"http:\/\/www.segplan.go.gov.br\/contatosiga\/ver\"><span style=\"color: #0000ff;\">Fale Conosco<\/span><\/a><\/td>\n<\/tr>\n<tr>\n<td style=\"background-color: #ff9900;\" align=\"center\" valign=\"center\"><strong><a title=\"P&aacute;gina inicial do SIGA - Sistema de Gest&atilde;o Administrativa.\" href=\"https:\/\/goias.gov.br\/administracao\/siga-sistema-de-gestao-administrativa\/\">SIGA<\/a><\/strong><\/td>\n<td style=\"background-color: #bbe8ff;\" align=\"center\" valign=\"center\" width=\"14%\"><a title=\"Integrada por &oacute;rg&atilde;os de assessoramento e aux&iacute;lio direto ao Chefe do Poder Executivo.\" href=\"https:\/\/goias.gov.br\/administracao\/siga-governadoria\/\">Governadoria<\/a><\/td>\n<td style=\"background-color: #bbe8ff;\" align=\"center\" valign=\"center\" width=\"14%\"><a title=\"Exerce compet&ecirc;ncias constitucionais, legais e regulamentares de aux&iacute;lio ao Governador.\" href=\"https:\/\/goias.gov.br\/administracao\/vg-1\/\">Vice-Governadoria<\/a><\/td>\n<td style=\"background-color: #bbe8ff;\" align=\"center\" valign=\"center\" width=\"14%\"><a title=\"&Oacute;rg&atilde;os de primeiro escal&atilde;o, respons&aacute;veis pela supervis&atilde;o e articula&ccedil;&atilde;o das atividades das respectivas &aacute;reas de atua&ccedil;&atilde;o, cabendo-lhes especificamente exercerem dentro do seu espa&ccedil;o institucional, pol&iacute;tico e administrativo, a formula&ccedil;&atilde;o das pol&iacute;ticas e diretrizes, a coordena&ccedil;&atilde;o de sua execu&ccedil;&atilde;o e a supervis&atilde;o geral das entidades jurisdicionadas.\" href=\"https:\/\/goias.gov.br\/administracao\/siga-secretarias\/\">Secretarias<\/a><\/td>\n<td style=\"background-color: #bbe8ff;\" align=\"center\" valign=\"center\" width=\"14%\"><a title=\"Entidades com personalidade jur&iacute;dica de direito p&uacute;blico, patrim&ocirc;nio e receita pr&oacute;prios e capacidade de auto-administra&ccedil;&atilde;o sob controle estatal, para executar atividades e servi&ccedil;os do Poder P&uacute;blico que, para melhor desempenho, requeiram gest&atilde;o administrativa e financeira descentralizada.\" href=\"https:\/\/goias.gov.br\/administracao\/siga-agencias\/\">Ag&ecirc;ncias\/Autarquias<\/a><\/td>\n<td style=\"background-color: #bbe8ff;\" align=\"center\" valign=\"center\" width=\"14%\"><a title=\"Entidade com personalidade jur&iacute;dica de direito p&uacute;blico, patrim&ocirc;nio e receita pr&oacute;prios e capacidade de auto-administra&ccedil;&atilde;o, sob controle estatal, para desenvolver atividades assistenciais, culturais, educacionais, de estudos e pesquisas, ou de apoio &agrave;s referidas atividades.\" href=\"?option=com_content&#038;view=article&#038;id=20126\">Funda&ccedil;&atilde;o<\/a><\/td>\n<td style=\"background-color: #bbe8ff;\" align=\"center\" valign=\"center\" width=\"14%\"><a title=\"Entidades institu&iacute;das sob a forma de sociedade por a&ccedil;&otilde;es, tendo em sua denomina&ccedil;&atilde;o &lsquo;Companhia&rsquo; ou &lsquo;S.A.&rsquo; (sociedade an&ocirc;nima), com o objetivo de realizar atividade econ&ocirc;mica ou servi&ccedil;o de interesse coletivo.\" href=\"https:\/\/goias.gov.br\/administracao\/siga-sociedades\/\">Sociedades de Economia Mista<\/a><\/td>\n<td style=\"background-color: #bbe8ff;\" align=\"center\" valign=\"center\" width=\"14%\"><a title=\"&Oacute;rg&atilde;os colegiados, que atuam e decidem pela manifesta&ccedil;&atilde;o conjunta e majorit&aacute;ria da vontade de seus membros compostos por representantes do Poder P&uacute;blico e da sociedade civil. S&atilde;o de natureza normativa, deliberativa, consultiva ou fiscalizadora.\" href=\"https:\/\/goias.gov.br\/administracao\/siga-conselhos\/\">Conselhos Estaduais<\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p><strong>Secretaria de Estado de Ci&ecirc;ncia e Tecnologia e Inova&ccedil;&atilde;o &#8211; SECTEC<\/strong><\/p>\n<p><a href=\"https:\/\/goias.gov.br\/administracao\/2011\/07\/20\/secretaria-de-estado-de-ciencia-e-tecnologia-e-inova-sectec-dados-gerais\/\"><span style=\"color: #0000ff;\">Dados Gerais<\/span><\/a> | <a href=\"https:\/\/goias.gov.br\/administracao\/2011\/07\/20\/sectec-2\/\"><span style=\"color: #0000ff;\">Compet&ecirc;ncias<\/span><\/a> | <a href=\"https:\/\/goias.gov.br\/administracao\/2011\/07\/20\/sectec-4\/\"><span style=\"color: #0000ff;\">Legisla&ccedil;&atilde;o<\/span><\/a> | <a href=\"https:\/\/goias.gov.br\/administracao\/2011\/07\/20\/secretaria-de-estado-de-ciencia-e-tecnologia-sectec-fundos\/\"><span style=\"color: #0000ff;\">Fundos<\/span><\/a> | <a href=\"http:\/\/www.sgc.goias.gov.br\/upload\/arquivos\/2012-01\/organograma_sectec-2011-r1.pdf\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\">Organograma<\/span><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Legisla&ccedil;&atilde;o:<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&#8211; <a href=\"http:\/\/www.gabinetecivil.go.gov.br\/pagina_decretos.php?id=12172\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\">Decreto n&ordm; 8.063, de 26 de dezembro de 2013<\/span><\/a> &#8211; <span style=\"font-size: 12px; font-family: arial; color: #000000;\">Disp&otilde;e sobre medidas de conten&ccedil;&atilde;o de despesas no &acirc;mbito do Poder Executivo e d&aacute; outras provid&ecirc;ncias.<\/span><\/p>\n<p style=\"text-align: justify;\" align=\"center\">&nbsp;<\/p>\n<p style=\"text-align: justify;\" align=\"center\"><span>&#8211;&nbsp;<\/span><span style=\"color: #0000ff;\"><a href=\"http:\/\/www.gabinetecivil.go.gov.br\/pagina_leis.php?id=11062\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\"><span>Lei n&ordm; 18.212,&nbsp;<\/span><span>de 12 de novembro de 2013<\/span><\/span><\/a><\/span><span>&nbsp;&#8211;&nbsp;<span>Altera o valor do subs&iacute;dio dos cargos em comiss&atilde;o que especifica.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\" align=\"center\">&nbsp;<\/p>\n<p style=\"text-align: justify;\" align=\"center\">&#8211; <a href=\"http:\/\/www.gabinetecivil.go.gov.br\/pagina_leis.php?id=11009\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\">Lei n&ordm; 18.197,&nbsp;<\/span><span style=\"color: #0000ff;\">de 1&ordm; de novembro de 2013<\/span><\/a> &#8211; Altera a&nbsp;<a href=\"http:\/\/www.gabinetecivil.go.gov.br\/pagina_leis.php?id=9899\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline;\"><span style=\"color: #0000ff;\"> Lei n&ordm; 17.257, de 25 de janeiro de 2011 &#8211; <\/span><\/span><\/a>que disp&otilde;e sobre a organiza&ccedil;&atilde;o administrativa do Poder Executivo e d&aacute; outras provid&ecirc;ncias.<\/p>\n<p>&nbsp;<\/p>\n<p>&#8211; <a href=\"http:\/\/www.gabinetecivil.go.gov.br\/pagina_decretos.php?id=11862\" target=\"_blank\" rel=\"noopener\"><span style=\"color: blue;\">Decreto n&ordm; 8.016, de 02 de outubro de 2013<\/span><\/a> &#8211; Introduz altera&ccedil;&otilde;es no <a href=\"http:\/\/www.gabinetecivil.goias.gov.br\/decretos\/numerados\/2011\/decreto_7513.htm\" target=\"_blank\" rel=\"noopener\"><span style=\"color: blue;\">Decreto n&ordm; 7.513, de 09 de dezembro de 2011<\/span><\/a> .<\/p>\n<p>&nbsp;<\/p>\n<p>&#8211; <a href=\"http:\/\/www.gabinetecivil.go.gov.br\/pagina_decretos.php?id=11588\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\">Decreto n&ordm; 7.959, de 08 de agosto de 2013<\/span><\/a> &#8211; Altera o <a href=\"http:\/\/www.gabinetecivil.go.gov.br\/pagina_decretos.php?id=9352\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\">Decreto n&ordm; 7.470, de 20 de outubro de 2011<\/span><\/a>, e d&aacute; outras provid&ecirc;ncias.<\/p>\n<p>&nbsp;<\/p>\n<p>&#8211; <a href=\"http:\/\/www.gabinetecivil.go.gov.br\/pagina_leis.php?id=10842\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\">Lei n&ordm; 18.036,&nbsp;<\/span><span style=\"color: #0000ff;\">de 07 de junho de 2013<\/span><\/a> &#8211; Institui p Programa Estadual de Apoio Financeiro &agrave; Educa&ccedil;&atilde;o Profissional &#8211; PROAFEP, no &acirc;mbito da Secretaria de Estado de Ci&ecirc;ncia e Tecnologia, e introduz altera&ccedil;&otilde;es na <a href=\"http:\/\/www.gabinetecivil.goias.gov.br\/leis_ordinarias\/2000\/lei_13666.htm\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline;\"><span style=\"color: #0000ff;\">Lei n&ordm; 13.666, de 27 de julho de 2000<\/span><\/span><\/a>.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"javascript:history.back()\">Voltar<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fale Conosco SIGA Governadoria Vice-Governadoria Secretarias Ag&ecirc;ncias\/Autarquias Funda&ccedil;&atilde;o Sociedades de Economia Mista Conselhos Estaduais &nbsp; Secretaria de Estado de Ci&ecirc;ncia e Tecnologia e Inova&ccedil;&atilde;o &#8211; SECTEC Dados Gerais | Compet&ecirc;ncias | Legisla&ccedil;&atilde;o | Fundos | Organograma &nbsp; Legisla&ccedil;&atilde;o: &nbsp; &#8211; Decreto n&ordm; 8.063, de 26 de dezembro de 2013 &#8211; Disp&otilde;e sobre medidas de conten&ccedil;&atilde;o [&hellip;]<\/p>\n","protected":false},"author":38,"featured_media":31,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[117],"tags":[],"class_list":["post-2600","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-orgaos-do-poder-executivo"],"rttpg_featured_image_url":{"full":["https:\/\/goias.gov.br\/administracao\/wp-content\/uploads\/sites\/27\/2011\/07\/logo_padrao-a16.jpg",200,110,false],"landscape":["https:\/\/goias.gov.br\/administracao\/wp-content\/uploads\/sites\/27\/2011\/07\/logo_padrao-a16.jpg",200,110,false],"portraits":["https:\/\/goias.gov.br\/administracao\/wp-content\/uploads\/sites\/27\/2011\/07\/logo_padrao-a16.jpg",200,110,false],"thumbnail":["https:\/\/goias.gov.br\/administracao\/wp-content\/uploads\/sites\/27\/2011\/07\/logo_padrao-a16-150x110.jpg",150,110,true],"medium":["https:\/\/goias.gov.br\/administracao\/wp-content\/uploads\/sites\/27\/2011\/07\/logo_padrao-a16.jpg",200,110,false],"large":["https:\/\/goias.gov.br\/administracao\/wp-content\/uploads\/sites\/27\/2011\/07\/logo_padrao-a16.jpg",200,110,false],"1536x1536":["https:\/\/goias.gov.br\/administracao\/wp-content\/uploads\/sites\/27\/2011\/07\/logo_padrao-a16.jpg",200,110,false],"2048x2048":["https:\/\/goias.gov.br\/administracao\/wp-content\/uploads\/sites\/27\/2011\/07\/logo_padrao-a16.jpg",200,110,false]},"rttpg_author":{"display_name":"gustavomartinsgomes","author_link":"https:\/\/goias.gov.br\/administracao\/author\/gustavomartinsgomes\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/administracao\/categoria\/orgaos-do-poder-executivo\/\" rel=\"category tag\">\u00d3rg\u00e3os do Poder Executivo<\/a>","rttpg_excerpt":"Fale Conosco SIGA Governadoria Vice-Governadoria Secretarias Ag&ecirc;ncias\/Autarquias Funda&ccedil;&atilde;o Sociedades de Economia Mista Conselhos Estaduais &nbsp; Secretaria de Estado de Ci&ecirc;ncia e Tecnologia e Inova&ccedil;&atilde;o &#8211; SECTEC Dados Gerais | Compet&ecirc;ncias | Legisla&ccedil;&atilde;o | Fundos | Organograma &nbsp; Legisla&ccedil;&atilde;o: &nbsp; &#8211; Decreto n&ordm; 8.063, de 26 de dezembro de 2013 &#8211; Disp&otilde;e sobre medidas de conten&ccedil;&atilde;o&hellip;","_links":{"self":[{"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/posts\/2600","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/comments?post=2600"}],"version-history":[{"count":1,"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/posts\/2600\/revisions"}],"predecessor-version":[{"id":14081,"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/posts\/2600\/revisions\/14081"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/media\/31"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/media?parent=2600"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/categories?post=2600"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/tags?post=2600"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}