{"id":20199,"date":"2024-03-15T14:08:55","date_gmt":"2024-03-15T17:08:55","guid":{"rendered":"https:\/\/goias.gov.br\/administracao\/?p=20199"},"modified":"2024-03-15T14:08:57","modified_gmt":"2024-03-15T17:08:57","slug":"servidor-estadual-saiba-como-emitir-o-comprovante-de-rendimentos-para-declaracao-de-imposto-de-renda","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/administracao\/servidor-estadual-saiba-como-emitir-o-comprovante-de-rendimentos-para-declaracao-de-imposto-de-renda\/","title":{"rendered":"Servidor estadual: saiba como emitir o comprovante de rendimentos para declara\u00e7\u00e3o de Imposto de Renda"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><em>S\u00f3 em 2023 foram quase 179 mil comprovantes gerados. Prazo para declara\u00e7\u00e3o vai at\u00e9 31 de maio<\/em><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1215\" height=\"911\" src=\"https:\/\/goias.gov.br\/administracao\/wp-content\/uploads\/sites\/27\/2024\/02\/WhatsApp-Image-2024-02-27-at-09.11.36.jpeg\" alt=\"\" class=\"wp-image-19979\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">O prazo para a declara\u00e7\u00e3o do imposto de renda teve in\u00edcio nesta sexta-feira, 15 de mar\u00e7o, e os informes de rendimentos dos servidores p\u00fablicos estaduais da administra\u00e7\u00e3o direta, aut\u00e1rquica e fundacional do poder Executivo est\u00e3o dispon\u00edveis no portal da Secretaria de Estado da Administra\u00e7\u00e3o (Sead) desde o final de fevereiro. Neste ano, as declara\u00e7\u00f5es podem ser submetidas at\u00e9 31 de maio utilizando o programa do Imposto de Renda dispon\u00edvel no <a href=\"https:\/\/www.gov.br\/receitafederal\/pt-br\">site da Receita Federal<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para acessar o comprovante, o servidor deve acessar a <a href=\"https:\/\/goias.gov.br\/administracao\">p\u00e1gina inicial da Sead<\/a>, rolar at\u00e9 o rodap\u00e9 da tela, e no menu \u201cServi\u00e7os\u201d, do lado esquerdo, clicar em \u201cComprovante de Rendimentos (Imposto de Renda \u2013 Pessoa F\u00edsica)\u201d. Para obter o comprovante, o usu\u00e1rio dever\u00e1 informar n\u00famero do CPF e senha \u2013 a mesma utilizada para consultar o contracheque. O link direto para emiss\u00e3o pode ser acessado <a href=\"http:\/\/folhapagamento.sistemas.go.gov.br\/folhapagamento\/control?cmd=ConsCedulaC&amp;ambiente=cedulac.%5D\">clicando aqui<\/a>. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Valores do Ipasgo<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O valor do plano de sa\u00fade Ipasgo, constante do quadro 7 (informa\u00e7\u00f5es complementares) do Comprovante de Rendimentos, refere-se exclusivamente aos descontos efetuados em folha de pagamento. Para obter os valores relativos \u00e0 coparticipa\u00e7\u00e3o nos procedimentos m\u00e9dicos do titular, agregados e outros, o servidor dever\u00e1 acessar o <a href=\"http:\/\/www.ipasgo.go.gov.br\">Portal do Ipasgo<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A Sead alerta ainda que com a cria\u00e7\u00e3o do Servi\u00e7o Social Aut\u00f4nomo do Ipasgo, os pagamentos realizados no per\u00edodo de janeiro a abril de 2023 devem ser informados no CNPJ 01.246.693\/0001-60 e os pagamentos realizados de maio a dezembro de 2023 no CNPJ 50.565.317\/0001-43, conforme informado no quadro 7 \u2013 informa\u00e7\u00f5es complementares). Caso os valores sejam lan\u00e7ados de forma unificada, a declara\u00e7\u00e3o poder\u00e1 ser retida em malha fiscal, por estar em desacordo com as informa\u00e7\u00f5es prestadas pelo Ipasgo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Comprovantes de servidores que receberam vencimentos por mais de um \u00f3rg\u00e3o em 2023<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante a emiss\u00e3o do comprovante, o servidor deve ficar atento ao selecionar o campo \u201c\u00f3rg\u00e3o\u201d. Caso conste o nome de duas ou mais pastas, deve-se emitir o comprovante de cada \u00f3rg\u00e3o habilitado na consulta. A situa\u00e7\u00e3o ocorre no caso de disposi\u00e7\u00e3o para outro \u00f3rg\u00e3o ou em circunst\u00e2ncia de aposentadoria, ocorridas em 2023, originando comprovantes distintos para cada entidade em que o servidor esteve lotado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Secretaria de Estado da Administra\u00e7\u00e3o \u2013 Governo de Goi\u00e1s<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>S\u00f3 em 2023 foram quase 179 mil comprovantes gerados. Prazo para declara\u00e7\u00e3o vai at\u00e9 31 de maio O prazo para a declara\u00e7\u00e3o do imposto de renda teve in\u00edcio nesta sexta-feira, 15 de mar\u00e7o, e os informes de rendimentos dos servidores p\u00fablicos estaduais da administra\u00e7\u00e3o direta, aut\u00e1rquica e fundacional do poder Executivo est\u00e3o dispon\u00edveis no portal [&hellip;]<\/p>\n","protected":false},"author":201,"featured_media":19596,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[121],"tags":[],"class_list":["post-20199","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-novas"],"rttpg_featured_image_url":{"full":["https:\/\/goias.gov.br\/administracao\/wp-content\/uploads\/sites\/27\/2024\/01\/PALACIO-PEDRO-LUDOVICO-9-891-1.jpg",700,393,false],"landscape":["https:\/\/goias.gov.br\/administracao\/wp-content\/uploads\/sites\/27\/2024\/01\/PALACIO-PEDRO-LUDOVICO-9-891-1.jpg",700,393,false],"portraits":["https:\/\/goias.gov.br\/administracao\/wp-content\/uploads\/sites\/27\/2024\/01\/PALACIO-PEDRO-LUDOVICO-9-891-1.jpg",700,393,false],"thumbnail":["https:\/\/goias.gov.br\/administracao\/wp-content\/uploads\/sites\/27\/2024\/01\/PALACIO-PEDRO-LUDOVICO-9-891-1.jpg",150,84,false],"medium":["https:\/\/goias.gov.br\/administracao\/wp-content\/uploads\/sites\/27\/2024\/01\/PALACIO-PEDRO-LUDOVICO-9-891-1.jpg",300,168,false],"large":["https:\/\/goias.gov.br\/administracao\/wp-content\/uploads\/sites\/27\/2024\/01\/PALACIO-PEDRO-LUDOVICO-9-891-1.jpg",700,393,false],"1536x1536":["https:\/\/goias.gov.br\/administracao\/wp-content\/uploads\/sites\/27\/2024\/01\/PALACIO-PEDRO-LUDOVICO-9-891-1.jpg",700,393,false],"2048x2048":["https:\/\/goias.gov.br\/administracao\/wp-content\/uploads\/sites\/27\/2024\/01\/PALACIO-PEDRO-LUDOVICO-9-891-1.jpg",700,393,false]},"rttpg_author":{"display_name":"thaisrcarvalho","author_link":"https:\/\/goias.gov.br\/administracao\/author\/thaisrcarvalho\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/administracao\/categoria\/noticias-novas\/\" rel=\"category tag\">Not\u00edcias<\/a>","rttpg_excerpt":"S\u00f3 em 2023 foram quase 179 mil comprovantes gerados. Prazo para declara\u00e7\u00e3o vai at\u00e9 31 de maio O prazo para a declara\u00e7\u00e3o do imposto de renda teve in\u00edcio nesta sexta-feira, 15 de mar\u00e7o, e os informes de rendimentos dos servidores p\u00fablicos estaduais da administra\u00e7\u00e3o direta, aut\u00e1rquica e fundacional do poder Executivo est\u00e3o dispon\u00edveis no portal&hellip;","_links":{"self":[{"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/posts\/20199","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/users\/201"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/comments?post=20199"}],"version-history":[{"count":1,"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/posts\/20199\/revisions"}],"predecessor-version":[{"id":20200,"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/posts\/20199\/revisions\/20200"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/media\/19596"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/media?parent=20199"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/categories?post=20199"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/tags?post=20199"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}