{"id":18556,"date":"2023-10-18T18:02:05","date_gmt":"2023-10-18T21:02:05","guid":{"rendered":"http:\/\/localhost\/wordpress\/administracao\/2023\/10\/18\/governo-de-goias-capacita-municipios-a-ofertarem-servicos-digitais\/"},"modified":"2023-12-28T18:25:56","modified_gmt":"2023-12-28T21:25:56","slug":"governo-de-goias-capacita-municipios-a-ofertarem-servicos-digitais","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/administracao\/governo-de-goias-capacita-municipios-a-ofertarem-servicos-digitais\/","title":{"rendered":"Governo de Goi\u00e1s capacita munic\u00edpios a ofertarem servi\u00e7os digitais"},"content":{"rendered":"<figure id=\"attachment_10\" aria-describedby=\"caption-attachment-10\" style=\"width: 1599px\" class=\"wp-caption alignnone\"><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-10\" title=\"Governo de Goi\u00e1s lan\u00e7a Rede de Apoio \u00e0 Transforma\u00e7\u00e3o Digital dos Munic\u00edpios Goianos, com objetivo de acelerar o processo de digitaliza\u00e7\u00e3o de servi\u00e7os p\u00fablicos aos cidad\u00e3os\" src=\"https:\/\/goias.gov.br\/administracao\/wp-content\/uploads\/sites\/27\/2023\/10\/INTERNA_-_GTD-75a.jpg\" alt=\"\" width=\"1599\" height=\"1066\" \/><figcaption id=\"caption-attachment-10\" class=\"wp-caption-text\">Governo de Goi\u00e1s lan\u00e7a Rede de Apoio \u00e0 Transforma\u00e7\u00e3o Digital dos Munic\u00edpios Goianos, com objetivo de acelerar o processo de digitaliza\u00e7\u00e3o de servi\u00e7os p\u00fablicos aos cidad\u00e3os<\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><em>Objetivo \u00e9 oferecer suporte para acelerar o processo de digitaliza\u00e7\u00e3o de servi\u00e7os p\u00fablicos de todo o estado<\/em><\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">Em parceria com a Uni\u00e3o, o Governo de Goi\u00e1s lan\u00e7ou, nesta quarta-feira (18\/10), a Rede de Apoio \u00e0 Transforma\u00e7\u00e3o Digital dos Munic\u00edpios Goianos, com o intuito de oferecer meios de facilitar a inclus\u00e3o e a transforma\u00e7\u00e3o digital, al\u00e9m de capacitar os gestores para que as cidades ofere\u00e7am servi\u00e7os p\u00fablicos de forma eletr\u00f4nica para \u00e0 popula\u00e7\u00e3o.<\/p>\n<p style=\"text-align: justify;\">O lan\u00e7amento ocorreu durante a oficina de Constru\u00e7\u00e3o Colaborativa da Estrat\u00e9gia Nacional de Governo Digital da regi\u00e3o Centro-Oeste, realizada na Assembleia Legislativa de Goi\u00e1s (Alego). \u00a0O evento foi realizado pelo Minist\u00e9rio da Gest\u00e3o e Inova\u00e7\u00e3o em Servi\u00e7os P\u00fablicos, em parceria com o Governo de Goi\u00e1s, por meio das secretarias de Ci\u00eancia, Tecnologia e Inova\u00e7\u00e3o (Secti), de Administra\u00e7\u00e3o (Sead) e Geral de Governo (SGG).<\/p>\n<p style=\"text-align: justify;\">O vice-governador Daniel Vilela ressaltou o fato de que Goi\u00e1s j\u00e1 \u00e9 o segundo no ranking dos estados mais digitalizados do Brasil, conforme levantamento da Associa\u00e7\u00e3o Brasileira de Entidades Estaduais de Tecnologia de Informa\u00e7\u00e3o e Comunica\u00e7\u00e3o (ABEP-TIC). \u201cSomos o segundo estado do pa\u00eds com a maior quantidade de servi\u00e7os digitais oferecidos \u00e0 popula\u00e7\u00e3o, mas os goianos s\u00e3o destemidos e queremos alcan\u00e7ar o primeiro lugar ainda neste ano. Nosso objetivo \u00e9 fazer com que todos os cidad\u00e3os goianos tenham os servi\u00e7os na palma da m\u00e3o\u201d, afirmou Vilela.<\/p>\n<p style=\"text-align: justify;\">Para conquistar esse objetivo, o titular da Secti, Jos\u00e9 Frederico Lyra Netto ressaltou que o trabalho integrado entre as secretarias \u00e9 fundamental. \u201cQueremos ajudar os munic\u00edpios a tornar a vida do cidad\u00e3o mais digital. Isso reduz custos e oferece servi\u00e7os melhores \u00e0 popula\u00e7\u00e3o. Este \u00e9 um trabalho feito de maneira integrada por tr\u00eas secretarias, sob o comando do governador Ronaldo Caiado, a fim de capacitar e promover a inclus\u00e3o digital das pessoas, usando as Escolas do Futuro e o Hub Goi\u00e1s, por exemplo; e o apoio aos munic\u00edpios\u201d, explicou.<\/p>\n<p>Francisco S\u00e9rvulo, titular da Sead, relatou que Goi\u00e1s tem clareza da dimens\u00e3o dos problemas que o Brasil enfrenta e que a estrat\u00e9gia de transforma\u00e7\u00e3o digital \u00e9 uma das vias para a supera\u00e7\u00e3o desses desafios. \u201cA constru\u00e7\u00e3o dessa pol\u00edtica deve ser colaborativa, partindo do governo federal, com articula\u00e7\u00e3o dos estados e munic\u00edpios com um objetivo em comum: simplificar o acesso do cidad\u00e3o aos servi\u00e7os p\u00fablicos, de forma moderna, segura e eficiente\u201d.<\/p>\n<p style=\"text-align: justify;\">Entre os servi\u00e7os oferecidos aos munic\u00edpios est\u00e3o: oficinas de capacita\u00e7\u00e3o para letramento e cidadania digital e seguran\u00e7a cibern\u00e9tica; conex\u00f5es e mentorias para a defini\u00e7\u00e3o de desafios de inova\u00e7\u00e3o digital aberta; acesso ao Sistema Eletr\u00f4nico de Informa\u00e7\u00f5es (SEI), do governo federal; e o oferecimento de solu\u00e7\u00f5es tecnol\u00f3gicas para pesquisas no campo de pol\u00edticas p\u00fablicas de inova\u00e7\u00e3o e transforma\u00e7\u00e3o digital no estado de Goi\u00e1s, fruto de parceria do Observat\u00f3rio de Inova\u00e7\u00e3o de Pol\u00edticas P\u00fablicas do Estado de Goi\u00e1s, ligado \u00e0 Secti, com a Universidade Federal de Goi\u00e1s (UFG).<\/p>\n<p style=\"text-align: justify;\"><strong>Nacional<\/strong><br \/>\nA iniciativa faz parte da Estrat\u00e9gia Nacional de Governo Digital, que ser\u00e1 publicada pelo Minist\u00e9rio da Gest\u00e3o e Inova\u00e7\u00e3o em Servi\u00e7os P\u00fablicos ainda neste ano. A estrat\u00e9gia \u00e9 fruto de cinco oficinas realizadas em todas as regi\u00f5es do pa\u00eds. A do Centro-Oeste foi a \u00faltima e Goi\u00e1s foi escolhido para receber o evento, que contou com a presen\u00e7a de representantes de estados e munic\u00edpios de Mato Grosso e Mato Grosso do Sul. A oficina recebeu mais de 300 inscri\u00e7\u00f5es.<\/p>\n<p style=\"text-align: justify;\">Representando a ministra Esther Dweck, a secret\u00e1ria ajunta de Governo Digital do MGI, Luanna Roncaratti, ressaltou a import\u00e2ncia da ades\u00e3o dos munic\u00edpios ao Gov.BR, plataforma do governo federal que vai reunir, de maneira integrada ao Expresso do Governo de Goi\u00e1s, servi\u00e7os digitais das tr\u00eas esferas de governo. \u201cO papel do minist\u00e9rio \u00e9 muito de fortalecer as capacidades estatais para que a gente consiga melhorar a oferta de servi\u00e7os p\u00fablicos de qualidade para a popula\u00e7\u00e3o. Para isso, oferecemos ferramentas como o Gov.BR.\u201d, finalizou.<\/p>\n<p style=\"text-align: justify;\"><em>Fotos: Jota Eur\u00edpedes<\/em><\/p>\n<p style=\"text-align: justify;\"><strong>Vice-Governadoria | Secretaria de Ci\u00eancia, Tecnologia e Inova\u00e7\u00e3o &#8211; Governo de Goi\u00e1s<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Objetivo \u00e9 oferecer suporte para acelerar o processo de digitaliza\u00e7\u00e3o de servi\u00e7os p\u00fablicos de todo o estado<\/p>\n","protected":false},"author":1,"featured_media":18667,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[121],"tags":[],"class_list":["post-18556","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-novas"],"rttpg_featured_image_url":{"full":["https:\/\/goias.gov.br\/administracao\/wp-content\/uploads\/sites\/27\/2023\/10\/CAPA_-_GTD-632-1.jpg",1600,1066,false],"landscape":["https:\/\/goias.gov.br\/administracao\/wp-content\/uploads\/sites\/27\/2023\/10\/CAPA_-_GTD-632-1.jpg",1600,1066,false],"portraits":["https:\/\/goias.gov.br\/administracao\/wp-content\/uploads\/sites\/27\/2023\/10\/CAPA_-_GTD-632-1.jpg",1600,1066,false],"thumbnail":["https:\/\/goias.gov.br\/administracao\/wp-content\/uploads\/sites\/27\/2023\/10\/CAPA_-_GTD-632-1.jpg",150,100,false],"medium":["https:\/\/goias.gov.br\/administracao\/wp-content\/uploads\/sites\/27\/2023\/10\/CAPA_-_GTD-632-1.jpg",300,200,false],"large":["https:\/\/goias.gov.br\/administracao\/wp-content\/uploads\/sites\/27\/2023\/10\/CAPA_-_GTD-632-1.jpg",1024,682,false],"1536x1536":["https:\/\/goias.gov.br\/administracao\/wp-content\/uploads\/sites\/27\/2023\/10\/CAPA_-_GTD-632-1.jpg",1536,1023,false],"2048x2048":["https:\/\/goias.gov.br\/administracao\/wp-content\/uploads\/sites\/27\/2023\/10\/CAPA_-_GTD-632-1.jpg",1600,1066,false]},"rttpg_author":{"display_name":"wagner.viana","author_link":"https:\/\/goias.gov.br\/administracao\/author\/wagner-viana\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/administracao\/categoria\/noticias-novas\/\" rel=\"category tag\">Not\u00edcias<\/a>","rttpg_excerpt":"Objetivo \u00e9 oferecer suporte para acelerar o processo de digitaliza\u00e7\u00e3o de servi\u00e7os p\u00fablicos de todo o estado","_links":{"self":[{"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/posts\/18556","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/comments?post=18556"}],"version-history":[{"count":1,"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/posts\/18556\/revisions"}],"predecessor-version":[{"id":18676,"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/posts\/18556\/revisions\/18676"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/media\/18667"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/media?parent=18556"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/categories?post=18556"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/tags?post=18556"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}