{"id":1509,"date":"2016-08-28T23:23:49","date_gmt":"2016-08-29T02:23:49","guid":{"rendered":"http:\/\/localhost\/multisites\/sead\/2016\/08\/28\/agetur-legislacao-2011\/"},"modified":"2023-10-18T16:24:34","modified_gmt":"2023-10-18T19:24:34","slug":"agetur-legislacao-2011","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/administracao\/agetur-legislacao-2011\/","title":{"rendered":"AGETUR &#8211; Legisla\u00e7\u00e3o 2011"},"content":{"rendered":"<p>&nbsp;<\/p>\n<table style=\"width: 100%;\" border=\"1\" cellspacing=\"1\" cellpadding=\"1\">\n<tbody>\n<tr>\n<td colspan=\"8\" align=\"right\">\n<p><a href=\"http:\/\/www.segplan.go.gov.br\/contatosiga\/ver\"><span style=\"color: #0000ff;\">Fale Conosco<\/span><\/a><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"background-color: #ff9900;\" align=\"center\" valign=\"middle\"><strong><a title=\"P&aacute;gina inicial do SIGA - Sistema de Gest&atilde;o Administrativa.\" href=\"https:\/\/goias.gov.br\/administracao\/siga-sistema-de-gestao-administrativa\/\">SIGA<\/a><\/strong><\/td>\n<td style=\"background-color: #bbe8ff;\" align=\"center\" valign=\"middle\" width=\"14%\"><a title=\"Integrada por &oacute;rg&atilde;os de assessoramento e aux&iacute;lio direto ao Chefe do Poder Executivo.\" href=\"https:\/\/goias.gov.br\/administracao\/siga-governadoria\/\">Governadoria<\/a><\/td>\n<td style=\"background-color: #bbe8ff;\" align=\"center\" valign=\"middle\" width=\"14%\"><a title=\"Exerce compet&ecirc;ncias constitucionais, legais e regulamentares de aux&iacute;lio ao Governador.\" href=\"https:\/\/goias.gov.br\/administracao\/vg-1\/\">Vice-Governadoria<\/a><\/td>\n<td style=\"background-color: #bbe8ff;\" align=\"center\" valign=\"middle\" width=\"14%\"><a title=\"&Oacute;rg&atilde;os de primeiro escal&atilde;o, respons&aacute;veis pela supervis&atilde;o e articula&ccedil;&atilde;o das atividades das respectivas &aacute;reas de atua&ccedil;&atilde;o, cabendo-lhes especificamente exercerem dentro do seu espa&ccedil;o institucional, pol&iacute;tico e administrativo, a formula&ccedil;&atilde;o das pol&iacute;ticas e diretrizes, a coordena&ccedil;&atilde;o de sua execu&ccedil;&atilde;o e a supervis&atilde;o geral das entidades jurisdicionadas.\" href=\"https:\/\/goias.gov.br\/administracao\/siga-secretarias\/\">Secretarias<\/a><\/td>\n<td style=\"background-color: #bbe8ff;\" align=\"center\" valign=\"middle\" width=\"14%\"><a title=\"Entidades com personalidade jur&iacute;dica de direito p&uacute;blico, patrim&ocirc;nio e receita pr&oacute;prios e capacidade de auto-administra&ccedil;&atilde;o sob controle estatal, para executar atividades e servi&ccedil;os do Poder P&uacute;blico que, para melhor desempenho, requeiram gest&atilde;o administrativa e financeira descentralizada.\" href=\"https:\/\/goias.gov.br\/administracao\/siga-agencias\/\">Ag&ecirc;ncias\/Autarquias<\/a><\/td>\n<td style=\"background-color: #bbe8ff;\" align=\"center\" valign=\"middle\" width=\"14%\"><a title=\"Entidade com personalidade jur&iacute;dica de direito p&uacute;blico, patrim&ocirc;nio e receita pr&oacute;prios e capacidade de auto-administra&ccedil;&atilde;o, sob controle estatal, para desenvolver atividades assistenciais, culturais, educacionais, de estudos e pesquisas, ou de apoio &agrave;s referidas atividades.\" href=\"?option=com_content&#038;view=article&#038;id=20126\">Funda&ccedil;&atilde;o<\/a><\/td>\n<td style=\"background-color: #bbe8ff;\" align=\"center\" valign=\"middle\" width=\"14%\"><a title=\"Entidades institu&iacute;das sob a forma de sociedade por a&ccedil;&otilde;es, tendo em sua denomina&ccedil;&atilde;o &lsquo;Companhia&rsquo; ou &lsquo;S.A.&rsquo; (sociedade an&ocirc;nima), com o objetivo de realizar atividade econ&ocirc;mica ou servi&ccedil;o de interesse coletivo.\" href=\"https:\/\/goias.gov.br\/administracao\/siga-sociedades\/\">Sociedades de Economia Mista<\/a><\/td>\n<td style=\"background-color: #bbe8ff;\" align=\"center\" valign=\"middle\" width=\"14%\"><a title=\"&Oacute;rg&atilde;os colegiados, que atuam e decidem pela manifesta&ccedil;&atilde;o conjunta e majorit&aacute;ria da vontade de seus membros compostos por representantes do Poder P&uacute;blico e da sociedade civil. S&atilde;o de natureza normativa, deliberativa, consultiva ou fiscalizadora.\" href=\"https:\/\/goias.gov.br\/administracao\/siga-conselhos\/\">Conselhos Estaduais<\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p><strong>Ag&ecirc;ncia Estadual de Turismo &#8211; Goi&aacute;s Turismo<\/strong><\/p>\n<p><a href=\"https:\/\/goias.gov.br\/administracao\/agencia-estadual-de-turismo-goias-turismo-dados-gerais\/\"><span style=\"color: #0000ff;\">Dados Gerais<\/span><\/a> | <a href=\"https:\/\/goias.gov.br\/administracao\/agencia-estadual-de-turismo-goias-turismo-regulamento\/\"><span style=\"color: #0000ff;\">Compet&ecirc;ncias<\/span><\/a> | <a href=\"https:\/\/goias.gov.br\/administracao\/agencia-estadualde-turismo-goias-turismo-legislacao\/\"><span style=\"color: #0000ff;\">Legisla&ccedil;&atilde;o<\/span><\/a> |&nbsp;<a href=\"http:\/\/www.sgc.goias.gov.br\/upload\/arquivos\/2012-01\/organograma_goiastur-2011-r1.pdf\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\">Organograma<\/span><\/a><strong><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Legisla&ccedil;&atilde;o:<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><span><span><span style=\"font-size: 12px; font-family: arial; color: #000000;\"><span style=\"font-size: 12px; font-family: arial; color: #000000;\">&#8211;&nbsp;<span style=\"color: #0000ff;\"><a href=\"http:\/\/www.gabinetecivil.go.gov.br\/pagina_leis.php?id=19548\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\">Lei n&ordm; 19.156, de 29 de dezembro de 2015<\/span><\/a><\/span>&nbsp;&#8211; Promove acr&eacute;scimos e altera&ccedil;&otilde;es na <span style=\"color: #0000ff;\"><a href=\"http:\/\/www.gabinetecivil.goias.gov.br\/leis_ordinarias\/1988\/lei_10460.htm\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\">Lei n&ordm; 10.460, de 22 de fevereiro de 1988<\/span><\/a><\/span>.<\/span><\/span><\/p>\n<p>&#8211;&nbsp;<\/span><span style=\"color: #0000ff;\"><a href=\"http:\/\/www.gabinetecivil.go.gov.br\/pagina_leis.php?id=18089\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\">Lei Complementar n&ordm; 118, de 06 de novembro de 2015<\/span><\/a><\/span><span>&nbsp;&#8211; Altera a&nbsp;<\/span><span style=\"color: #0000ff;\"><a href=\"http:\/\/www.gabinetecivil.go.gov.br\/pagina_leis.php?id=9258\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\">Lei Complementar n&ordm; 77, de 22 de janeiro de 2010<\/span><\/a><\/span><span>, que disp&otilde;e sobre a adequa&ccedil;&atilde;o do Regime Pr&oacute;prio de Previd&ecirc;ncia dos Servidores -RPPS-, e d&aacute; outras provid&ecirc;ncias.<\/span><\/p>\n<p><\/span><\/p>\n<p><span><span>&#8211;&nbsp;<\/span><span style=\"color: #0000ff;\"><a href=\"http:\/\/www.sgc.goias.gov.br\/upload\/arquivos\/2015-10\/instrucao-normativa-009-2015-gab.pdf\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\">Instru&ccedil;&atilde;o Normativa n&ordm; 09-2015\/SEGPLAN (29\/10\/2015)<\/span><\/a><\/span><span>, disp&otilde;e sobre normas complementares do sistema de registro e controle eletr&ocirc;nico&nbsp; da frequencia dos servidores p&uacute;blicos da Administra&ccedil;&atilde;o direta, aut&aacute;rquica e fundacional do Poder Executivo e d&aacute; outras provid&ecirc;ncias.<\/span><\/p>\n<p>&#8211; <span style=\"color: #0000ff;\"><a href=\"http:\/\/www.agecom.go.gov.br\/PDF\/2015\/10\/14\/002.pdf\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\">Portaria n&ordm; 68\/2015<\/span><\/a><\/span> &#8211; Atribui&ccedil;&otilde;es de Servidores junto &agrave; estrutura organizacional b&aacute;sica.<\/p>\n<p>&#8211;&nbsp;<\/span><span style=\"color: #0000ff;\"><a href=\"http:\/\/www.gabinetecivil.go.gov.br\/pagina_leis.php?id=16852\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\">Lei n&ordm; 19.019, de 25 de setembro de 2015<\/span><\/a><\/span><span>&nbsp;&#8211; Disp&otilde;e sobre o controle de frequ&ecirc;ncia do servidor no &acirc;mbito da administra&ccedil;&atilde;o direta, aut&aacute;rquica e fundacional do Poder Executivo.<\/span><\/p>\n<p>&#8211;&nbsp;<span style=\"color: #0000ff;\"><a href=\"http:\/\/www.gabinetecivil.go.gov.br\/pagina_decretos.php?id=13502\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\">Decreto n&ordm; 8.386, de 10 de junho de 2015<\/span><\/a><\/span>&nbsp;&#8211; Introduz altera&ccedil;&otilde;es no&nbsp;<span style=\"color: #0000ff;\"><a href=\"http:\/\/www.gabinetecivil.go.gov.br\/pagina_decretos.php?id=13342\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\">Decreto n&ordm; 8.320, de 12 de fevereiro de 2015<\/span><\/a><\/span>.<\/p>\n<p>&#8211;&nbsp;<span style=\"color: #0000ff;\"><a href=\"http:\/\/www.gabinetecivil.go.gov.br\/pagina_leis.php?id=13312\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\">Lei n&ordm; 18.861, de 01 de junho de 2015<\/span><\/a><\/span>&nbsp;&#8211;&nbsp;Altera as Leis nos&nbsp;<span style=\"color: #0000ff;\"><a href=\"http:\/\/www.gabinetecivil.goias.gov.br\/leis_ordinarias\/1988\/lei_10460.htm\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\">10.460, de 22 de fevereiro de 1988<\/span><\/a><\/span>, e&nbsp;<span style=\"color: #0000ff;\"><a href=\"http:\/\/www.gabinetecivil.goias.gov.br\/leis_ordinarias\/2001\/lei_13909.htm\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\">13.909, de 25 de setembro de 2001<\/span><\/a><\/span>, e d&aacute; outras provid&ecirc;ncias.<\/p>\n<p>&#8211;&nbsp;<span style=\"color: #0000ff;\"><a href=\"http:\/\/www.gabinetecivil.go.gov.br\/pagina_decretos.php?id=13342\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\">Decreto n&ordm; 8.320, de 12 de fevereiro de 2015<\/span><\/a><\/span>&nbsp;&#8211;&nbsp;Estabelece medidas de conten&ccedil;&atilde;o de gastos com pessoal e outras despesas correntes, no &acirc;mbito da administra&ccedil;&atilde;o direta, aut&aacute;rquica e fundacional do Poder Executivo e d&aacute; outras provid&ecirc;ncias.<\/p>\n<p><span style=\"color: #0000ff;\"><span style=\"color: #000000;\">&#8211; <span style=\"color: #0000ff;\"><a href=\"http:\/\/www.gabinetecivil.go.gov.br\/pagina_leis.php?id=11816\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\">Lei n&ordm; 18.746, de 29 de dezembro de 2014<\/span><\/a><\/span> &#8211; Introduz altera&ccedil;&otilde;es na <span style=\"color: #0000ff;\"><a href=\"http:\/\/www.gabinetecivil.goias.gov.br\/leis_ordinarias\/2011\/lei_17257.htm\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\">Lei n&ordm; 17.257, de 25 de janeiro de 2011<\/span><\/a><\/span>, adequando-a &agrave;s prescri&ccedil;&otilde;es da Lei n&ordm; 18.687, de 03 de dezembro de 2014, e d&aacute; outra provid&ecirc;ncias.<\/span><\/span><\/p>\n<p>&nbsp;<span style=\"color: #0000ff;\"><span style=\"color: #000000;\"><span style=\"color: #0000ff;\"><span style=\"color: #000000;\">&#8211; <span style=\"color: #0000ff;\"><a href=\"http:\/\/www.gabinetecivil.go.gov.br\/pagina_leis.php?id=11764\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\">Lei n&ordm; 18.687, de 03 de dezembro de 2014<\/span><\/a><\/span> &#8211; Disp&otilde;e sobre a reorganiza&ccedil;&atilde;o administrativa do Poder Executivo de d&aacute; outras provid&ecirc;ncias.<br \/><\/span><\/span><\/span><\/span><\/p>\n<p>&#8211; <span style=\"color: #0000ff;\"><a href=\"http:\/\/www.gabinetecivil.go.gov.br\/pagina_decretos.php?id=13167\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\">Decreto n&ordm; 8.276, de 13 de novembro de 2014<\/span><\/a><\/span> &#8211; Altera o <a href=\"http:\/\/www.gabinetecivil.goias.gov.br\/decretos\/numerados\/2014\/decreto_8170.htm\" target=\"_blank\" rel=\"noopener\"><span style=\"color: blue;\">Decreto n&ordm; 8.170, de 02 de junho de 2014,<\/span><\/a> que regulamenta a<a href=\"http:\/\/www.gabinetecivil.goias.gov.br\/leis_ordinarias\/2012\/lei_17867.htm\" target=\"_blank\" rel=\"noopener\"><span style=\"color: blue;\"> Lei n&ordm; 17.867, de 20 de dezembro de 2012<\/span><\/a>, que institui o Modelo de Gest&atilde;o para Resultados no &acirc;mbito do Poder Executivo e d&aacute; outras provid&ecirc;ncias.<\/p>\n<p>&#8211; <span style=\"color: #0000ff;\"><a href=\"http:\/\/www.gabinetecivil.go.gov.br\/pagina_decretos.php?id=13149\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\">Decreto n&ordm; 8.274, de 13 de novembro de 2014<\/span><\/a><\/span> &#8211; Altera o <a href=\"http:\/\/www.gabinetecivil.goias.gov.br\/decretos\/numerados\/2014\/decreto_8170.htm\" target=\"_blank\" rel=\"noopener\"><span style=\"color: blue;\">Decreto n&ordm; 8.170, de 02 de junho de 2014,<\/span><\/a> que regulamenta a<a href=\"http:\/\/www.gabinetecivil.goias.gov.br\/leis_ordinarias\/2012\/lei_17867.htm\" target=\"_blank\" rel=\"noopener\"><span style=\"color: blue;\"> Lei n&ordm; 17.867, de 20 de dezembro de 2012<\/span><\/a>, que institui o Modelo de Gest&atilde;o para Resultados no &acirc;mbito do Poder Executivo e d&aacute; outras provid&ecirc;ncias.<\/p>\n<p>&#8211; <span style=\"color: #0000ff;\"><a href=\"http:\/\/www.gabinetecivil.go.gov.br\/pagina_decretos.php?id=13150\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\">Decreto n&ordm; 8.273, de 13 de novembro de 2014<\/span><\/a><\/span> &#8211; Disp&otilde;e sobre exonera&ccedil;&atilde;o e dispensa de pessoal e extin&ccedil;&atilde;o de cargos e fun&ccedil;&otilde;es, na forma que especifica, e d&aacute; outras provid&ecirc;ncias.<\/p>\n<p><span style=\"color: blue;\"><span style=\"font-size: 12px; font-family: arial; color: #000000;\"><span style=\"color: blue;\">&#8211; <a href=\"http:\/\/www.gabinetecivil.go.gov.br\/pagina_leis.php?id=11363\"><span style=\"color: blue;\">Lei n&ordm; 18.445, de 03 de abril de 2014<\/span><\/a><\/span> &#8211; Altera a <a href=\"http:\/\/www.gabinetecivil.goias.gov.br\/leis_ordinarias\/2011\/lei_17257.htm\"><span style=\"color: blue;\">Lei n&ordm; 17.257, de 25 de janeiro de 2011<\/span><\/a>, que disp&otilde;e sobre a organiza&ccedil;&atilde;o administrativa do Poder Executivo e d&aacute; outras provid&ecirc;ncias.<\/p>\n<p><\/span><\/span><\/p>\n<p><span style=\"color: blue;\"><span style=\"font-size: 12px; font-family: arial; color: #000000;\">&#8211; <\/span><\/span><a href=\"http:\/\/www.gabinetecivil.go.gov.br\/pagina_decretos.php?id=12383\" target=\"_blank\" rel=\"noopener\"><span style=\"color: blue;\">Decreto n&ordm; 8.144, de 08 de abril de 2014<\/span><\/a> &#8211; Introduz altera&ccedil;&otilde;es no <a href=\"http:\/\/www.gabinetecivil.goias.gov.br\/decretos\/numerados\/2011\/decreto_7424.htm\" target=\"_blank\" rel=\"noopener\"><span style=\"color: blue;\">Decreto n&ordm; 7.424, de 11 de agosto de 2011<\/span><\/a>, que aprova o Regulamento da Goi&aacute;s Turismo &#8211; Ag&ecirc;ncia Goiana de Turismo.<\/p>\n<p><span style=\"font-size: 12px; font-family: arial; color: #000000;\"><span style=\"font-size: 12px; font-family: arial; color: #000000;\"><br \/>&#8211; <span style=\"font-size: 12px; font-family: arial; color: #000000;\"><a href=\"http:\/\/www.gabinetecivil.go.gov.br\/pagina_leis.php?id=11117\" target=\"_blank\" rel=\"noopener\"><span style=\"color: blue;\">Lei n&ordm; 18.286, de 30 de dezembro de 2013<\/span><\/a> &#8211; Modifica a organiza&ccedil;&atilde;o administrativa do Poder Executivo e d&aacute; outras provid&ecirc;ncias.<\/span><\/span><\/span><\/p>\n<p>&#8211; <a href=\"http:\/\/www.gabinetecivil.go.gov.br\/pagina_decretos.php?id=12172\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\">Decreto n&ordm; 8.063, de 26 de dezembro de 2013<\/span><\/a> &#8211; <span style=\"font-size: 12px; font-family: arial; color: #000000;\">Disp&otilde;e sobre medidas de conten&ccedil;&atilde;o de despesas no &acirc;mbito do Poder Executivo e d&aacute; outras provid&ecirc;ncias.<\/span><\/p>\n<p><strong><strong><span style=\"color: #0000ff;\"><br \/>&#8211; <\/span><\/strong><\/strong><a href=\"http:\/\/www.gabinetecivil.go.gov.br\/pagina_decretos.php?id=11071\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\">Decreto n&ordm; 7.851 de 27 de mar&ccedil;o de 2013<\/span><\/a>&nbsp; &#8211; Introduz altera&ccedil;&otilde;es no Regulamento da GOI&Aacute;S TURISMO &#8211; Ag&ecirc;ncia Goiania de Turismo, aprovado pelo <span style=\"color: #0000ff;\"><a href=\"http:\/\/www.gabinetecivil.goias.gov.br\/decretos\/numerados\/2011\/decreto_7424.htm\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\">Decreto n&ordm; 7.424, de 11 de agosto de 2011<\/span><\/a><\/span>.<\/p>\n<p>&nbsp;<\/p>\n<p>&#8211; <a href=\"http:\/\/www.gabinetecivil.go.gov.br\/pagina_leis.php?id=10536\"><span style=\"color: #0000ff;\">Lei n&ordm; 17.855, de 10 de dezembro de 2012<\/span><\/a> &#8211; Introduz altera&ccedil;&otilde;es nas <a href=\"http:\/\/www.gabinetecivil.goias.gov.br\/leis_ordinarias\/1995\/lei_12758.htm\"><span style=\"color: #0000ff;\">Leis n&ordm; 12.758, de 12 de dezembro de 1995<\/span><\/a>, <a href=\"http:\/\/www.gabinetecivil.goias.gov.br\/leis_ordinarias\/1997\/lei_13049.htm\"><span style=\"color: #0000ff;\">13.049, de 16 de abril de 1997&nbsp;<\/span><\/a> e <a href=\"http:\/\/www.gabinetecivil.goias.gov.br\/leis_ordinarias\/1999\/lei_13550.htm\"><span style=\"color: #0000ff;\">13.550 de 11 de novembro de 1999.<\/span><\/a><\/p>\n<p>&#8211; <a href=\"http:\/\/www.gabinetecivil.go.gov.br\/pagina_leis.php?id=10381\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\">Lei n&ordm; 17.707, de 09 de julho de 2012<\/span><\/a> &#8211; Cria as unidades administrativas complementares e os correspondentes cargos de provimento em comiss&atilde;o que especifica, na Goi&aacute;s Turismo &ndash; Ag&ecirc;ncia Goiana de Turismo.<\/p>\n<p><strong><\/strong><br \/>&#8211; <span style=\"text-decoration: underline;\"><a href=\"http:\/\/www.gabinetecivil.go.gov.br\/pagina_decretos.php?id=10100\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\">Decreto n&ordm; 7.628, de&nbsp;23 de&nbsp;maio de 2012<\/span><\/a><\/span>&nbsp;&#8211; Disp&otilde;e sobre a institui&ccedil;&atilde;o da Unidade de Coordena&ccedil;&atilde;o de Projeto &#8211; UCP, em Goi&aacute;s, do Programa Nacional de Desenvolvimento do Turismo &#8211; PRODETUR, e d&aacute; outras provid&ecirc;ncias.<\/p>\n<p>&#8211; <a href=\"http:\/\/www.gabinetecivil.go.gov.br\/pagina_decretos.php?id=9584\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\">Decreto n&ordm; 7.496, de 29 de novembro de 2011<\/span><\/a> &#8211; Altera o Regulamento da Ag&ecirc;ncia Goiana de Turismo &#8211; GOI&Aacute;S TURISMO &#8211; , aprovado pelo <strong><a href=\"http:\/\/www.gabinetecivil.go.gov.br\/pagina_decretos.php?id=8960\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\">&#8211; Decreto n&ordm; 7.424, de 11 de agosto de 2011.<\/span><\/a><\/strong><\/p>\n<p>&#8211; <a href=\"http:\/\/www.gabinetecivil.go.gov.br\/pagina_leis.php?id=10088\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\">Lei n&ordm; 17.433, de 10 de outubro de 2011<\/span><\/a> &#8211; Altera a <a href=\"http:\/\/www.gabinetecivil.goias.gov.br\/leis_ordinarias\/2009\/lei_16478.htm\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\">Lei n&ordm; 16.478, de 10 de fevereiro de 2009<\/span><\/a>, que institui a Pol&iacute;tica Estadual de Desenvolvimento do Turismo Rural.<\/p>\n<p>&#8211; <strong><a href=\"http:\/\/www.gabinetecivil.go.gov.br\/pagina_decretos.php?id=8960\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\">Decreto n&ordm; 7.424, de 11 de agosto de 2011<\/span><\/a><\/strong> &#8211; <strong><span style=\"color: #000000;\">Aprova o Regulamento da GOI&Aacute;S TURISMO &#8211; Ag&ecirc;ncia Goiana de Turismo e d&aacute; outras provid&ecirc;ncias.<\/p>\n<p><\/span><\/strong><\/p>\n<p>&#8211; <a href=\"http:\/\/www.gabinetecivil.go.gov.br\/pagina_leis.php?id=10024\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\">Lei n&ordm; 17.372, de 14 de julho de 2011<\/span><\/a> &#8211; Introduz altera&ccedil;&otilde;es na <a href=\"http:\/\/www.gabinetecivil.go.gov.br\/pagina_leis.php?id=9899\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\">Lei n&ordm; 17.257, de 25 de janeiro de 2011 <\/span><\/a>e d&aacute; outras provid&ecirc;ncias.<\/p>\n<p>&#8211; <span style=\"text-decoration: underline;\"><a href=\"http:\/\/www.gabinetecivil.goias.gov.br\/decretos\/numerados\/2011\/decreto_7351.htm\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\">Decreto n&ordm; 7.351, de 25 de maio de 2011<\/span><\/a><\/span> &#8211; Institui o Programa Estadual de Incentivo &agrave; Avia&ccedil;&atilde;o Regional &#8211; VOE GOI&Aacute;S &#8211; e d&aacute; outras provid&ecirc;ncias<\/p>\n<p>&#8211; <span style=\"text-decoration: underline;\"><a href=\"http:\/\/www.gabinetecivil.goias.gov.br\/pagina_decretos.php?id=8295\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\">Decreto n&ordm; 7.272, de 28 de Mar&ccedil;o de 2011<\/span><\/a><\/span> &#8211; Institui as unidades administrativas complementares da GOI&Aacute;S TURISMO &#8211; Ag&ecirc;ncia Estadual de Turismo e d&aacute; outras provid&ecirc;ncias.<\/p>\n<p>&#8211; <a href=\"http:\/\/www.gabinetecivil.go.gov.br\/pagina_leis.php?id=9899\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline;\"><span style=\"color: #0000ff;\">Lei n&ordm; 17.257, de 25 de janeiro de 2011<\/span><\/span><\/a> &#8211; Disp&otilde;e sobre a organiza&ccedil;&atilde;o da administrativa do Poder Executivo e d&aacute; outras provid&ecirc;ncias<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"javascript:history.back()\">Voltar<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Fale Conosco SIGA Governadoria Vice-Governadoria Secretarias Ag&ecirc;ncias\/Autarquias Funda&ccedil;&atilde;o Sociedades de Economia Mista Conselhos Estaduais &nbsp; Ag&ecirc;ncia Estadual de Turismo &#8211; Goi&aacute;s Turismo Dados Gerais | Compet&ecirc;ncias | Legisla&ccedil;&atilde;o |&nbsp;Organograma &nbsp; Legisla&ccedil;&atilde;o: &nbsp; &#8211;&nbsp;Lei n&ordm; 19.156, de 29 de dezembro de 2015&nbsp;&#8211; Promove acr&eacute;scimos e altera&ccedil;&otilde;es na Lei n&ordm; 10.460, de 22 de fevereiro de [&hellip;]<\/p>\n","protected":false},"author":38,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[124],"tags":[],"class_list":["post-1509","post","type-post","status-publish","format-standard","hentry","category-siga"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"gustavomartinsgomes","author_link":"https:\/\/goias.gov.br\/administracao\/author\/gustavomartinsgomes\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/administracao\/categoria\/siga\/\" rel=\"category tag\">SIGA<\/a>","rttpg_excerpt":"&nbsp; Fale Conosco SIGA Governadoria Vice-Governadoria Secretarias Ag&ecirc;ncias\/Autarquias Funda&ccedil;&atilde;o Sociedades de Economia Mista Conselhos Estaduais &nbsp; Ag&ecirc;ncia Estadual de Turismo &#8211; Goi&aacute;s Turismo Dados Gerais | Compet&ecirc;ncias | Legisla&ccedil;&atilde;o |&nbsp;Organograma &nbsp; Legisla&ccedil;&atilde;o: &nbsp; &#8211;&nbsp;Lei n&ordm; 19.156, de 29 de dezembro de 2015&nbsp;&#8211; Promove acr&eacute;scimos e altera&ccedil;&otilde;es na Lei n&ordm; 10.460, de 22 de fevereiro de&hellip;","_links":{"self":[{"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/posts\/1509","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/comments?post=1509"}],"version-history":[{"count":1,"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/posts\/1509\/revisions"}],"predecessor-version":[{"id":13656,"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/posts\/1509\/revisions\/13656"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/media?parent=1509"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/categories?post=1509"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/tags?post=1509"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}