{"id":1351,"date":"2014-01-16T15:01:44","date_gmt":"2014-01-16T17:01:44","guid":{"rendered":"http:\/\/localhost\/multisites\/sead\/2014\/01\/16\/secult-legislacao-2006-a-2010\/"},"modified":"2023-10-18T16:26:10","modified_gmt":"2023-10-18T19:26:10","slug":"secult-legislacao-2006-a-2010","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/administracao\/secult-legislacao-2006-a-2010\/","title":{"rendered":"SECULT &#8211; Legisla\u00e7\u00e3o 2006 a 2010"},"content":{"rendered":"<table style=\"width: 100%;\" border=\"1\" cellspacing=\"1\" cellpadding=\"1\">\n<tbody>\n<tr>\n<td colspan=\"8\" align=\"right\"><a href=\"http:\/\/www.segplan.go.gov.br\/contatosiga\/ver\"><span style=\"color: #0000ff;\">Fale Conosco<\/span><\/a><\/td>\n<\/tr>\n<tr>\n<td style=\"background-color: #ff9900;\" align=\"center\" valign=\"center\"><strong><a title=\"P&aacute;gina inicial do SIGA - Sistema de Gest&atilde;o Administrativa.\" href=\"https:\/\/goias.gov.br\/administracao\/siga-sistema-de-gestao-administrativa\/\">SIGA<\/a><\/strong><\/td>\n<td style=\"background-color: #bbe8ff;\" align=\"center\" valign=\"center\" width=\"14%\"><a title=\"Integrada por &oacute;rg&atilde;os de assessoramento e aux&iacute;lio direto ao Chefe do Poder Executivo.\" href=\"https:\/\/goias.gov.br\/administracao\/siga-governadoria\/\">Governadoria<\/a><\/td>\n<td style=\"background-color: #bbe8ff;\" align=\"center\" valign=\"center\" width=\"14%\"><a title=\"Exerce compet&ecirc;ncias constitucionais, legais e regulamentares de aux&iacute;lio ao Governador.\" href=\"https:\/\/goias.gov.br\/administracao\/vg-1\/\">Vice-Governadoria<\/a><\/td>\n<td style=\"background-color: #bbe8ff;\" align=\"center\" valign=\"center\" width=\"14%\"><a title=\"&Oacute;rg&atilde;os de primeiro escal&atilde;o, respons&aacute;veis pela supervis&atilde;o e articula&ccedil;&atilde;o das atividades das respectivas &aacute;reas de atua&ccedil;&atilde;o, cabendo-lhes especificamente exercerem dentro do seu espa&ccedil;o institucional, pol&iacute;tico e administrativo, a formula&ccedil;&atilde;o das pol&iacute;ticas e diretrizes, a coordena&ccedil;&atilde;o de sua execu&ccedil;&atilde;o e a supervis&atilde;o geral das entidades jurisdicionadas.\" href=\"https:\/\/goias.gov.br\/administracao\/siga-secretarias\/\">Secretarias<\/a><\/td>\n<td style=\"background-color: #bbe8ff;\" align=\"center\" valign=\"center\" width=\"14%\"><a title=\"Entidades com personalidade jur&iacute;dica de direito p&uacute;blico, patrim&ocirc;nio e receita pr&oacute;prios e capacidade de auto-administra&ccedil;&atilde;o sob controle estatal, para executar atividades e servi&ccedil;os do Poder P&uacute;blico que, para melhor desempenho, requeiram gest&atilde;o administrativa e financeira descentralizada.\" href=\"https:\/\/goias.gov.br\/administracao\/siga-agencias\/\">Ag&ecirc;ncias\/Autarquias<\/a><\/td>\n<td style=\"background-color: #bbe8ff;\" align=\"center\" valign=\"center\" width=\"14%\"><a title=\"Entidade com personalidade jur&iacute;dica de direito p&uacute;blico, patrim&ocirc;nio e receita pr&oacute;prios e capacidade de auto-administra&ccedil;&atilde;o, sob controle estatal, para desenvolver atividades assistenciais, culturais, educacionais, de estudos e pesquisas, ou de apoio &agrave;s referidas atividades.\" href=\"?option=com_content&#038;view=article&#038;id=20126\">Funda&ccedil;&atilde;o<\/a><\/td>\n<td style=\"background-color: #bbe8ff;\" align=\"center\" valign=\"center\" width=\"14%\"><a title=\"Entidades institu&iacute;das sob a forma de sociedade por a&ccedil;&otilde;es, tendo em sua denomina&ccedil;&atilde;o &lsquo;Companhia&rsquo; ou &lsquo;S.A.&rsquo; (sociedade an&ocirc;nima), com o objetivo de realizar atividade econ&ocirc;mica ou servi&ccedil;o de interesse coletivo.\" href=\"https:\/\/goias.gov.br\/administracao\/siga-sociedades\/\">Sociedades de Economia Mista<\/a><\/td>\n<td style=\"background-color: #bbe8ff;\" align=\"center\" valign=\"center\" width=\"14%\"><a title=\"&Oacute;rg&atilde;os colegiados, que atuam e decidem pela manifesta&ccedil;&atilde;o conjunta e majorit&aacute;ria da vontade de seus membros compostos por representantes do Poder P&uacute;blico e da sociedade civil. S&atilde;o de natureza normativa, deliberativa, consultiva ou fiscalizadora.\" href=\"https:\/\/goias.gov.br\/administracao\/siga-conselhos\/\">Conselhos Estaduais<\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p><strong>Secretaria de Estado da Cultura &#8211; SECULT <\/strong><\/p>\n<p><a href=\"https:\/\/goias.gov.br\/administracao\/?p=82\"><span style=\"color: #0000ff;\">Dados Gerais<\/span><\/a> | <a href=\"https:\/\/goias.gov.br\/administracao\/secretaria-de-estado-da-cultura-secult-competencias\/\"><span style=\"color: #0000ff;\">Compet&ecirc;ncias<\/span><\/a> | <a href=\"https:\/\/goias.gov.br\/administracao\/secretaria-de-estado-da-cultura-secult-legislacao\/\"><span style=\"color: #0000ff;\">Legisla&ccedil;&atilde;o<\/span><\/a> | <a href=\"https:\/\/goias.gov.br\/administracao\/2012\/05\/10\/secretaria-de-estado-da-cultura-secult-fundos\/\"><span style=\"color: #0000ff;\">Fundos<\/span><\/a> | <a href=\"http:\/\/www.sgc.goias.gov.br\/upload\/arquivos\/2012-01\/organograma_secult-2011-r1.pdf\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\">Organograma<\/span><\/a><\/p>\n<p><span>&nbsp;<\/span><\/p>\n<p><span><strong>Legisla&ccedil;&atilde;o:<\/strong> <\/span><\/p>\n<p>&nbsp;<\/p>\n<p>&#8211; <a href=\"http:\/\/www.gabinetecivil.goias.gov.br\/pagina_decretos.php?id=6398\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\">Decreto n&ordm; 6.916 de 08 de maio de 2009<\/span><\/a> &#8211;&nbsp;Aprova o Regulamento da Ag&ecirc;ncia Goiana de Cultura Pedro Ludovico Teixeira e d&aacute; outras provid&ecirc;ncias.<\/p>\n<p>&nbsp;<\/p>\n<p>&#8211; <a href=\"http:\/\/www.gabinetecivil.goias.gov.br\/decretos\/numerados\/2008\/decreto_6834.htm\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\">Decreto n&ordm; 6.834&nbsp;de 05 de dezembro de 2008<\/span><\/a> &#8211; Institui Grupo de Trabalho para elabora&ccedil;&atilde;o de projeto de revitaliza&ccedil;&atilde;o da Pra&ccedil;a Pedro Ludovico Teixeira, desta Capital.<\/p>\n<p>&nbsp;<\/p>\n<p>&#8211; <a href=\"http:\/\/www.gabinetecivil.goias.gov.br\/leis_ordinarias\/2008\/lei_16272.htm\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\">Lei n&ordm; 16.272&nbsp;de 30 de maio de 2008<\/span><\/a> &#8211; Disp&otilde;e sobre a organiza&ccedil;&atilde;o da administra&ccedil;&atilde;o direta, aut&aacute;rquica e fundacional do Poder Executivo.<\/p>\n<p>&nbsp;<\/p>\n<p>&#8211; <a href=\"http:\/\/www.gabinetecivil.goias.gov.br\/leis_ordinarias\/2006\/lei_15795.htm\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\">Lei n&ordm; 15.795, de 04 de setembro de 2006<\/span><\/a> &#8211; Introduz altera&ccedil;&otilde;es na estrutura organizacional b&aacute;sica e complementar da Ag&ecirc;ncia Goiana de Cultura Pedro Ludovico Teixeira &#8211; AGEPEL, e d&aacute; outras provid&ecirc;ncias.<\/p>\n<p>&bull; A Ger&ecirc;ncia Executiva do Centro de Cultural, passa a denominar Ger&ecirc;ncia Executiva dos Centros Culturais (inc. II, do anexo XXXIII, da <a href=\"http:\/\/www.gabinetecivil.go.gov.br\/pagina_leis.php?id=7029\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\">Lei Delegada n.&ordm; 08, de 15 de outubro de 2003<\/span><\/a>;<\/p>\n<p>&bull; Cria as Ger&ecirc;ncias: Centro Cultural Oscar Niemeyer e do Centro Cultural Labibe Faiad de Catal&atilde;o.<\/p>\n<p>&nbsp;<\/p>\n<p>&#8211; <a href=\"http:\/\/www.gabinetecivil.goias.gov.br\/leis_ordinarias\/2006\/lei_15676.htm\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\">Lei n&ordm; 15.676, de 02 de junho de 2006 <\/span><\/a>&#8211; Disp&otilde;e sobre o Quadro Permanente de Pessoal e o Plano de Cargos e Remunera&ccedil;&atilde;o, dos servidores da Ag&ecirc;ncia Goiana de Cultura Pedro Ludovico Teixeira, e d&aacute; outras provid&ecirc;ncias.<\/p>\n<p>&nbsp;<\/p>\n<p>&#8211; <a href=\"http:\/\/www.gabinetecivil.goias.gov.br\/leis_ordinarias\/2006\/lei_15647.htm\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\">Lei n.&ordm; 15.647, de 09 de maio de 2006<\/span><\/a> &ndash; Cria o Centro Cultural Oscar Niemeyer e d&aacute; nome aos espa&ccedil;os culturais nele edificados.<\/p>\n<p>&nbsp;<\/p>\n<p>&#8211; <a href=\"http:\/\/www.gabinetecivil.goias.gov.br\/leis_ordinarias\/2006\/lei_15633.htm\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\">Lei n&ordm; 15.633, de 30 de mar&ccedil;o de 2006<\/span><\/a>, vinculado a Ag&ecirc;ncia Goiana Pedro Ludovico Teixeira &ndash; AGEPEL, destinado a apoiar a pesquisa, a cria&ccedil;&atilde;o e a circula&ccedil;&atilde;o de obras de arte e a realiza&ccedil;&atilde;o de atividades art&iacute;sticas e\/ou culturais.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"javascript:history.back()\">Voltar<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fale Conosco SIGA Governadoria Vice-Governadoria Secretarias Ag&ecirc;ncias\/Autarquias Funda&ccedil;&atilde;o Sociedades de Economia Mista Conselhos Estaduais &nbsp; Secretaria de Estado da Cultura &#8211; SECULT Dados Gerais | Compet&ecirc;ncias | Legisla&ccedil;&atilde;o | Fundos | Organograma &nbsp; Legisla&ccedil;&atilde;o: &nbsp; &#8211; Decreto n&ordm; 6.916 de 08 de maio de 2009 &#8211;&nbsp;Aprova o Regulamento da Ag&ecirc;ncia Goiana de Cultura Pedro Ludovico [&hellip;]<\/p>\n","protected":false},"author":38,"featured_media":31,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[117],"tags":[],"class_list":["post-1351","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-orgaos-do-poder-executivo"],"rttpg_featured_image_url":{"full":["https:\/\/goias.gov.br\/administracao\/wp-content\/uploads\/sites\/27\/2011\/07\/logo_padrao-a16.jpg",200,110,false],"landscape":["https:\/\/goias.gov.br\/administracao\/wp-content\/uploads\/sites\/27\/2011\/07\/logo_padrao-a16.jpg",200,110,false],"portraits":["https:\/\/goias.gov.br\/administracao\/wp-content\/uploads\/sites\/27\/2011\/07\/logo_padrao-a16.jpg",200,110,false],"thumbnail":["https:\/\/goias.gov.br\/administracao\/wp-content\/uploads\/sites\/27\/2011\/07\/logo_padrao-a16-150x110.jpg",150,110,true],"medium":["https:\/\/goias.gov.br\/administracao\/wp-content\/uploads\/sites\/27\/2011\/07\/logo_padrao-a16.jpg",200,110,false],"large":["https:\/\/goias.gov.br\/administracao\/wp-content\/uploads\/sites\/27\/2011\/07\/logo_padrao-a16.jpg",200,110,false],"1536x1536":["https:\/\/goias.gov.br\/administracao\/wp-content\/uploads\/sites\/27\/2011\/07\/logo_padrao-a16.jpg",200,110,false],"2048x2048":["https:\/\/goias.gov.br\/administracao\/wp-content\/uploads\/sites\/27\/2011\/07\/logo_padrao-a16.jpg",200,110,false]},"rttpg_author":{"display_name":"gustavomartinsgomes","author_link":"https:\/\/goias.gov.br\/administracao\/author\/gustavomartinsgomes\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/administracao\/categoria\/orgaos-do-poder-executivo\/\" rel=\"category tag\">\u00d3rg\u00e3os do Poder Executivo<\/a>","rttpg_excerpt":"Fale Conosco SIGA Governadoria Vice-Governadoria Secretarias Ag&ecirc;ncias\/Autarquias Funda&ccedil;&atilde;o Sociedades de Economia Mista Conselhos Estaduais &nbsp; Secretaria de Estado da Cultura &#8211; SECULT Dados Gerais | Compet&ecirc;ncias | Legisla&ccedil;&atilde;o | Fundos | Organograma &nbsp; Legisla&ccedil;&atilde;o: &nbsp; &#8211; Decreto n&ordm; 6.916 de 08 de maio de 2009 &#8211;&nbsp;Aprova o Regulamento da Ag&ecirc;ncia Goiana de Cultura Pedro Ludovico&hellip;","_links":{"self":[{"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/posts\/1351","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/comments?post=1351"}],"version-history":[{"count":1,"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/posts\/1351\/revisions"}],"predecessor-version":[{"id":13571,"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/posts\/1351\/revisions\/13571"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/media\/31"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/media?parent=1351"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/categories?post=1351"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/tags?post=1351"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}