{"id":12629,"date":"2023-04-20T11:29:07","date_gmt":"2023-04-20T14:29:07","guid":{"rendered":"http:\/\/localhost\/multisites\/sead\/2023\/04\/20\/sead-lanca-mba-em-projetos-e-processos-para-servidores-lotados-na-pasta\/"},"modified":"2023-10-18T15:29:25","modified_gmt":"2023-10-18T18:29:25","slug":"sead-lanca-mba-em-projetos-e-processos-para-servidores-lotados-na-pasta","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/administracao\/sead-lanca-mba-em-projetos-e-processos-para-servidores-lotados-na-pasta\/","title":{"rendered":"Sead lan\u00e7a MBA em Projetos e Processos para servidores lotados na pasta"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-12628\" src=\"https:\/\/goias.gov.br\/administracao\/wp-content\/uploads\/sites\/27\/2023\/04\/20-04-2023_MBA_ESCOLA_DE_GOVERNO-48d.jpeg\" alt=\"\" width=\"1600\" height=\"1201\" srcset=\"https:\/\/goias.gov.br\/administracao\/wp-content\/uploads\/sites\/27\/2023\/04\/20-04-2023_MBA_ESCOLA_DE_GOVERNO-48d.jpeg 1600w, https:\/\/goias.gov.br\/administracao\/wp-content\/uploads\/sites\/27\/2023\/04\/20-04-2023_MBA_ESCOLA_DE_GOVERNO-48d-300x225.jpeg 300w, https:\/\/goias.gov.br\/administracao\/wp-content\/uploads\/sites\/27\/2023\/04\/20-04-2023_MBA_ESCOLA_DE_GOVERNO-48d-1024x769.jpeg 1024w, https:\/\/goias.gov.br\/administracao\/wp-content\/uploads\/sites\/27\/2023\/04\/20-04-2023_MBA_ESCOLA_DE_GOVERNO-48d-768x576.jpeg 768w, https:\/\/goias.gov.br\/administracao\/wp-content\/uploads\/sites\/27\/2023\/04\/20-04-2023_MBA_ESCOLA_DE_GOVERNO-48d-1536x1153.jpeg 1536w, https:\/\/goias.gov.br\/administracao\/wp-content\/uploads\/sites\/27\/2023\/04\/20-04-2023_MBA_ESCOLA_DE_GOVERNO-48d-600x450.jpeg 600w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/><\/p>\n<p style=\"text-align: justify;\"><em>Inscri&ccedil;&otilde;es para o processo seletivo, com 10 vagas, ser&atilde;o abertas na pr&oacute;xima ter&ccedil;a-feira (25); outras duas especializa&ccedil;&otilde;es ter&atilde;o editais publicados em breve<\/em><\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">A Secretaria de Estado da Administra&ccedil;&atilde;o (Sead) publicou, nesta quinta-feira (20\/4), edital de lan&ccedil;amento do MBA em Projetos e Processos direcionado aos servidores que atuam no &oacute;rg&atilde;o. As inscri&ccedil;&otilde;es para o processo seletivo ser&atilde;o gratuitas, no per&iacute;odo de 25 de abril a 2 de maio, no portal https:<a href=\"http:\/\/selecao.go.gov.br\/\">\/\/selecao.go.gov.br\/<\/a>.<\/p>\n<p style=\"text-align: justify;\">S&atilde;o ofertadas 10 vagas e a sele&ccedil;&atilde;o se dar&aacute; por an&aacute;lise curricular e entrevista com o candidato. O curso ser&aacute; conduzido pelo Instituto de P&oacute;s-Gradua&ccedil;&atilde;o e Especializa&ccedil;&atilde;o (Ipog).<\/p>\n<p style=\"text-align: justify;\">A prefer&ecirc;ncia &eacute; para servidores que j&aacute; atuam em &aacute;reas afins do curso e que se beneficiar&atilde;o dos conte&uacute;dos para a pr&aacute;tica profissional di&aacute;ria. A publica&ccedil;&atilde;o do resultado definitivo, com a lista dos selecionados, est&aacute; prevista para maio.<\/p>\n<p style=\"text-align: justify;\"><strong>Novas turmas<\/strong><\/p>\n<p style=\"text-align: justify;\">Al&eacute;m do MBA em Projetos e Processos, a Sead publicar&aacute;, em breve, editais para outras duas p&oacute;s-gradua&ccedil;&otilde;es: Licita&ccedil;&otilde;es e Contrata&ccedil;&otilde;es P&uacute;blicas (On-line) e para Ci&ecirc;ncia de Dados. Os cursos tamb&eacute;m ser&atilde;o direcionados a servidores lotados na pasta.<\/p>\n<p style=\"text-align: justify;\">Ao ofertar conte&uacute;dos dessa natureza, em &aacute;reas espec&iacute;ficas e essenciais para administra&ccedil;&atilde;o, o objetivo do Governo de Goi&aacute;s &eacute; alcan&ccedil;ar a excel&ecirc;ncia em setores primordiais para a promo&ccedil;&atilde;o de pol&iacute;ticas p&uacute;blicas e entregas &agrave; popula&ccedil;&atilde;o.<\/p>\n<p style=\"text-align: justify;\">A primeira especializa&ccedil;&atilde;o ofertada pela Sead, essa por meio da Escola de Governo, em Gest&atilde;o, Pessoas e Inova&ccedil;&atilde;o, teve in&iacute;cio no ano passado e deve ser finalizada neste ano. Foram selecionados 40 servidores, a maioria com atua&ccedil;&atilde;o em Gest&atilde;o P&uacute;blica, com o intuito de desenvolver e aprimorar compet&ecirc;ncias e habilidades essenciais para articular, gerir e pensar a a&ccedil;&atilde;o governamental de forma profissional, estrat&eacute;gica e inovadora.<\/p>\n<p style=\"text-align: justify;\"><strong>Secretaria da Administra&ccedil;&atilde;o &#8211; Governo de Goi&aacute;s<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Inscri&ccedil;&otilde;es para o processo seletivo, com 10 vagas, ser&atilde;o abertas na pr&oacute;xima ter&ccedil;a-feira (25); outras duas especializa&ccedil;&otilde;es ter&atilde;o editais publicados em breve<\/p>\n","protected":false},"author":67,"featured_media":12628,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[121],"tags":[],"class_list":["post-12629","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-novas"],"rttpg_featured_image_url":{"full":["https:\/\/goias.gov.br\/administracao\/wp-content\/uploads\/sites\/27\/2023\/04\/20-04-2023_MBA_ESCOLA_DE_GOVERNO-48d.jpeg",1600,1201,false],"landscape":["https:\/\/goias.gov.br\/administracao\/wp-content\/uploads\/sites\/27\/2023\/04\/20-04-2023_MBA_ESCOLA_DE_GOVERNO-48d.jpeg",1600,1201,false],"portraits":["https:\/\/goias.gov.br\/administracao\/wp-content\/uploads\/sites\/27\/2023\/04\/20-04-2023_MBA_ESCOLA_DE_GOVERNO-48d.jpeg",1600,1201,false],"thumbnail":["https:\/\/goias.gov.br\/administracao\/wp-content\/uploads\/sites\/27\/2023\/04\/20-04-2023_MBA_ESCOLA_DE_GOVERNO-48d-150x150.jpeg",150,150,true],"medium":["https:\/\/goias.gov.br\/administracao\/wp-content\/uploads\/sites\/27\/2023\/04\/20-04-2023_MBA_ESCOLA_DE_GOVERNO-48d-300x225.jpeg",300,225,true],"large":["https:\/\/goias.gov.br\/administracao\/wp-content\/uploads\/sites\/27\/2023\/04\/20-04-2023_MBA_ESCOLA_DE_GOVERNO-48d-1024x769.jpeg",1024,769,true],"1536x1536":["https:\/\/goias.gov.br\/administracao\/wp-content\/uploads\/sites\/27\/2023\/04\/20-04-2023_MBA_ESCOLA_DE_GOVERNO-48d-1536x1153.jpeg",1536,1153,true],"2048x2048":["https:\/\/goias.gov.br\/administracao\/wp-content\/uploads\/sites\/27\/2023\/04\/20-04-2023_MBA_ESCOLA_DE_GOVERNO-48d.jpeg",1600,1201,false]},"rttpg_author":{"display_name":"rogeriolm","author_link":"https:\/\/goias.gov.br\/administracao\/author\/rogeriolm\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/administracao\/categoria\/noticias-novas\/\" rel=\"category tag\">Not\u00edcias<\/a>","rttpg_excerpt":"Inscri&ccedil;&otilde;es para o processo seletivo, com 10 vagas, ser&atilde;o abertas na pr&oacute;xima ter&ccedil;a-feira (25); outras duas especializa&ccedil;&otilde;es ter&atilde;o editais publicados em breve","_links":{"self":[{"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/posts\/12629","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/users\/67"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/comments?post=12629"}],"version-history":[{"count":1,"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/posts\/12629\/revisions"}],"predecessor-version":[{"id":14699,"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/posts\/12629\/revisions\/14699"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/media\/12628"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/media?parent=12629"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/categories?post=12629"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/tags?post=12629"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}