{"id":10653,"date":"2021-04-29T11:49:53","date_gmt":"2021-04-29T14:49:53","guid":{"rendered":"http:\/\/localhost\/multisites\/sead\/2021\/04\/29\/vapt-vupt-itaucu-tem-atendimento-suspenso-para-reforma-a-partir-de-segunda-feira-3-5\/"},"modified":"2023-10-18T15:35:01","modified_gmt":"2023-10-18T18:35:01","slug":"vapt-vupt-itaucu-tem-atendimento-suspenso-para-reforma-a-partir-de-segunda-feira-3-5","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/administracao\/vapt-vupt-itaucu-tem-atendimento-suspenso-para-reforma-a-partir-de-segunda-feira-3-5\/","title":{"rendered":"Vapt Vupt Itau\u00e7u tem atendimento suspenso para reforma a partir de segunda-feira (3\/5)"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-10652\" src=\"https:\/\/goias.gov.br\/administracao\/wp-content\/uploads\/sites\/27\/2021\/04\/29-04_-ITAUCU-d99.png\" alt=\"\" width=\"1920\" height=\"1080\" srcset=\"https:\/\/goias.gov.br\/administracao\/wp-content\/uploads\/sites\/27\/2021\/04\/29-04_-ITAUCU-d99.png 1920w, https:\/\/goias.gov.br\/administracao\/wp-content\/uploads\/sites\/27\/2021\/04\/29-04_-ITAUCU-d99-300x169.png 300w, https:\/\/goias.gov.br\/administracao\/wp-content\/uploads\/sites\/27\/2021\/04\/29-04_-ITAUCU-d99-1024x576.png 1024w, https:\/\/goias.gov.br\/administracao\/wp-content\/uploads\/sites\/27\/2021\/04\/29-04_-ITAUCU-d99-768x432.png 768w, https:\/\/goias.gov.br\/administracao\/wp-content\/uploads\/sites\/27\/2021\/04\/29-04_-ITAUCU-d99-1536x864.png 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/p>\n<p>Os atendimentos no Vapt Vupt de Itau&ccedil;u ser&atilde;o suspensos, temporariamente, a partir da pr&oacute;xima segunda-feira (3\/5). Os servi&ccedil;os ser&atilde;o interrompidos para a realiza&ccedil;&atilde;o de reforma da unidade, que est&aacute; prevista para ocorrer at&eacute; o dia 31 de maio.&nbsp;<\/p>\n<p>Durante as obras, os documentos de CNH e cart&otilde;es Ipasgo estar&atilde;o dispon&iacute;veis na ag&ecirc;ncia Vapt Vupt de Inhumas, a partir das 14 horas da pr&oacute;xima segunda-feira (3\/5). N&atilde;o h&aacute; necessidade de agendamento para a retirada desses itens. A ag&ecirc;ncia de Inhumas est&aacute; localizada na Rua Goi&aacute;s, quadra 44, lote 12, n&deg; 139, no Setor Central.<\/p>\n<p>A previs&atilde;o &eacute; de que os servi&ccedil;os na unidade de Itau&ccedil;u sejam retomados no dia 1&deg; de junho. Os usu&aacute;rios que desejarem atendimento no local ap&oacute;s essa data devem fazer agendamento pr&eacute;vio no portal <a href=\"https:\/\/vaptvupt.go.gov.br\/\">vaptvupt.go.gov.br<\/a>.<\/p>\n<p><strong>Secretaria da Administra&ccedil;&atilde;o (Sead) &ndash; Governo de Goi&aacute;s<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os atendimentos no Vapt Vupt de Itau&ccedil;u ser&atilde;o suspensos, temporariamente, a partir da pr&oacute;xima segunda-feira (3\/5). Os servi&ccedil;os ser&atilde;o interrompidos para a realiza&ccedil;&atilde;o de reforma da unidade, que est&aacute; prevista para ocorrer at&eacute; o dia 31 de maio.&nbsp; Durante as obras, os documentos de CNH e cart&otilde;es Ipasgo estar&atilde;o dispon&iacute;veis na ag&ecirc;ncia Vapt Vupt de [&hellip;]<\/p>\n","protected":false},"author":61,"featured_media":10652,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[121],"tags":[],"class_list":["post-10653","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-novas"],"rttpg_featured_image_url":{"full":["https:\/\/goias.gov.br\/administracao\/wp-content\/uploads\/sites\/27\/2021\/04\/29-04_-ITAUCU-d99.png",1920,1080,false],"landscape":["https:\/\/goias.gov.br\/administracao\/wp-content\/uploads\/sites\/27\/2021\/04\/29-04_-ITAUCU-d99.png",1920,1080,false],"portraits":["https:\/\/goias.gov.br\/administracao\/wp-content\/uploads\/sites\/27\/2021\/04\/29-04_-ITAUCU-d99.png",1920,1080,false],"thumbnail":["https:\/\/goias.gov.br\/administracao\/wp-content\/uploads\/sites\/27\/2021\/04\/29-04_-ITAUCU-d99-150x150.png",150,150,true],"medium":["https:\/\/goias.gov.br\/administracao\/wp-content\/uploads\/sites\/27\/2021\/04\/29-04_-ITAUCU-d99-300x169.png",300,169,true],"large":["https:\/\/goias.gov.br\/administracao\/wp-content\/uploads\/sites\/27\/2021\/04\/29-04_-ITAUCU-d99-1024x576.png",1024,576,true],"1536x1536":["https:\/\/goias.gov.br\/administracao\/wp-content\/uploads\/sites\/27\/2021\/04\/29-04_-ITAUCU-d99-1536x864.png",1536,864,true],"2048x2048":["https:\/\/goias.gov.br\/administracao\/wp-content\/uploads\/sites\/27\/2021\/04\/29-04_-ITAUCU-d99.png",1920,1080,false]},"rttpg_author":{"display_name":"mariatoledo","author_link":"https:\/\/goias.gov.br\/administracao\/author\/mariatoledo\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/administracao\/categoria\/noticias-novas\/\" rel=\"category tag\">Not\u00edcias<\/a>","rttpg_excerpt":"Os atendimentos no Vapt Vupt de Itau&ccedil;u ser&atilde;o suspensos, temporariamente, a partir da pr&oacute;xima segunda-feira (3\/5). Os servi&ccedil;os ser&atilde;o interrompidos para a realiza&ccedil;&atilde;o de reforma da unidade, que est&aacute; prevista para ocorrer at&eacute; o dia 31 de maio.&nbsp; Durante as obras, os documentos de CNH e cart&otilde;es Ipasgo estar&atilde;o dispon&iacute;veis na ag&ecirc;ncia Vapt Vupt de&hellip;","_links":{"self":[{"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/posts\/10653","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/comments?post=10653"}],"version-history":[{"count":1,"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/posts\/10653\/revisions"}],"predecessor-version":[{"id":15518,"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/posts\/10653\/revisions\/15518"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/media\/10652"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/media?parent=10653"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/categories?post=10653"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/administracao\/wp-json\/wp\/v2\/tags?post=10653"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}