

{"id":43454,"date":"2024-11-15T09:37:00","date_gmt":"2024-11-15T12:37:00","guid":{"rendered":"https:\/\/goias.gov.br\/abc\/?p=43454"},"modified":"2024-11-15T23:05:39","modified_gmt":"2024-11-16T02:05:39","slug":"brasil-central-presente-na-abertura-do-natal-do-bem-com-cobertura-ao-vivo","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/abc\/brasil-central-presente-na-abertura-do-natal-do-bem-com-cobertura-ao-vivo\/","title":{"rendered":"Brasil Central presente na abertura do Natal do Bem com cobertura ao vivo"},"content":{"rendered":"\n<p>O governador Ronaldo Caiado e a primeira-dama e Gracinha Caiado conduziram a abertura no <em>Natal do Bem<\/em> 2024, nesta quinta-feira (14), com transmiss\u00e3o ao vivo pela TV Brasil Central. Primeiro foi realizado um evento para prefeitos e primeiras-damas de munic\u00edpios do interior do estado. Caiado falou que o Natal do Bem cresce a cada ano, com mais de 300 atra\u00e7\u00f5es passando pelos 53 dias de evento no Centro Cultural Oscar Niemeyer. \u201cIsso tudo \u00e9 para mostrar o carinho que temos com as fam\u00edlias que est\u00e3o tendo a oportunidade de ver hoje o maior natal gratuito do pa\u00eds\u201d, pontuou.<\/p>\n\n\n\n<p>Ele comentou tamb\u00e9m sobre a distribui\u00e7\u00e3o de mais de 500 mil brinquedos para todos os munic\u00edpios goianos. Na sequ\u00eancia, foi realizada a cerim\u00f4nia oficial de lan\u00e7amento, com o acendimento das luzes e parada natalina, com personagens e chegada do Papai Noel. \u201cToda a equipe do Goi\u00e1s Social trabalhou durante meses para que esse natal se tornasse realidade\u201d, explicou a primeira-dama Gracinha Caiado.<\/p>\n\n\n\n<p>A <a href=\"https:\/\/goias.gov.br\/abc\/brasil-central-projeta-grande-cobertura-do-natal-do-bem-deste-ano\/\">TV Brasil Central preparou cobertura jornal\u00edstica especial para o Natal do Bem<\/a>, com transmiss\u00f5es especiais e programas tem\u00e1ticos. O <em>Natal do Bem 2024<\/em> tem 3 milh\u00f5es de pontos de luz, roda gigante, linhas de \u00f4nibus exclusivas e estacionamento com 12 mil vagas. A previs\u00e3o de p\u00fablico \u00e9 de 1,5 milh\u00e3o de pessoas at\u00e9 o dia 5 de janeiro em um espa\u00e7o de mais de 30 mil metros quadrados, com decora\u00e7\u00e3o especial e atra\u00e7\u00f5es di\u00e1rias.<\/p>\n\n\n\n<p><strong>ABC Digital<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed aligncenter is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"LAN\u00c7AMENTO NATAL DO BEM 2024 | 14\/11\/2024\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/6sjdr5s5Fw4?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>O governador Ronaldo Caiado e a primeira-dama e Gracinha Caiado conduziram a abertura no Natal do Bem 2024, nesta quinta-feira (14), com transmiss\u00e3o ao vivo pela TV Brasil Central. Primeiro foi realizado um evento para prefeitos e primeiras-damas de munic\u00edpios do interior do estado. Caiado falou que o Natal do Bem cresce a cada ano, [&hellip;]<\/p>\n","protected":false},"author":380,"featured_media":43466,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[39],"tags":[57],"class_list":["post-43454","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-programacao"],"rttpg_featured_image_url":{"full":["https:\/\/goias.gov.br\/abc\/wp-content\/uploads\/sites\/23\/2024\/11\/2024.11.15_TBC_NATAL.jpg",1200,600,false],"landscape":["https:\/\/goias.gov.br\/abc\/wp-content\/uploads\/sites\/23\/2024\/11\/2024.11.15_TBC_NATAL.jpg",1200,600,false],"portraits":["https:\/\/goias.gov.br\/abc\/wp-content\/uploads\/sites\/23\/2024\/11\/2024.11.15_TBC_NATAL.jpg",1200,600,false],"thumbnail":["https:\/\/goias.gov.br\/abc\/wp-content\/uploads\/sites\/23\/2024\/11\/2024.11.15_TBC_NATAL-150x150.jpg",150,150,true],"medium":["https:\/\/goias.gov.br\/abc\/wp-content\/uploads\/sites\/23\/2024\/11\/2024.11.15_TBC_NATAL-300x150.jpg",300,150,true],"large":["https:\/\/goias.gov.br\/abc\/wp-content\/uploads\/sites\/23\/2024\/11\/2024.11.15_TBC_NATAL-1024x512.jpg",1024,512,true],"1536x1536":["https:\/\/goias.gov.br\/abc\/wp-content\/uploads\/sites\/23\/2024\/11\/2024.11.15_TBC_NATAL.jpg",1200,600,false],"2048x2048":["https:\/\/goias.gov.br\/abc\/wp-content\/uploads\/sites\/23\/2024\/11\/2024.11.15_TBC_NATAL.jpg",1200,600,false]},"rttpg_author":{"display_name":"nadialima","author_link":"https:\/\/goias.gov.br\/abc\/author\/nadialima\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/abc\/categoria\/institucional\/noticias\/\" rel=\"category tag\">Not\u00edcias<\/a>","rttpg_excerpt":"O governador Ronaldo Caiado e a primeira-dama e Gracinha Caiado conduziram a abertura no Natal do Bem 2024, nesta quinta-feira (14), com transmiss\u00e3o ao vivo pela TV Brasil Central. Primeiro foi realizado um evento para prefeitos e primeiras-damas de munic\u00edpios do interior do estado. Caiado falou que o Natal do Bem cresce a cada ano,&hellip;","_links":{"self":[{"href":"https:\/\/goias.gov.br\/abc\/wp-json\/wp\/v2\/posts\/43454","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/abc\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/abc\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/abc\/wp-json\/wp\/v2\/users\/380"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/abc\/wp-json\/wp\/v2\/comments?post=43454"}],"version-history":[{"count":2,"href":"https:\/\/goias.gov.br\/abc\/wp-json\/wp\/v2\/posts\/43454\/revisions"}],"predecessor-version":[{"id":43481,"href":"https:\/\/goias.gov.br\/abc\/wp-json\/wp\/v2\/posts\/43454\/revisions\/43481"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/abc\/wp-json\/wp\/v2\/media\/43466"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/abc\/wp-json\/wp\/v2\/media?parent=43454"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/abc\/wp-json\/wp\/v2\/categories?post=43454"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/abc\/wp-json\/wp\/v2\/tags?post=43454"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}