

{"id":20731,"date":"2023-09-04T08:31:33","date_gmt":"2023-09-04T11:31:33","guid":{"rendered":"https:\/\/siteshom.goias.gov.br\/abc\/caiado-participa-de-forum-empresarial-nos-estados-unidos\/"},"modified":"2023-09-04T08:31:33","modified_gmt":"2023-09-04T11:31:33","slug":"caiado-participa-de-forum-empresarial-nos-estados-unidos","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/abc\/caiado-participa-de-forum-empresarial-nos-estados-unidos\/","title":{"rendered":"Caiado participa de f\u00f3rum empresarial nos Estados Unidos"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-20730\" src=\"https:\/\/goias.gov.br\/abc\/wp-content\/uploads\/sites\/23\/2023\/09\/04.09_JBC_LIDE-dee.jpg\" alt=\"\" width=\"1280\" height=\"720\" srcset=\"https:\/\/goias.gov.br\/abc\/wp-content\/uploads\/sites\/23\/2023\/09\/04.09_JBC_LIDE-dee.jpg 1280w, https:\/\/goias.gov.br\/abc\/wp-content\/uploads\/sites\/23\/2023\/09\/04.09_JBC_LIDE-dee-300x169.jpg 300w, https:\/\/goias.gov.br\/abc\/wp-content\/uploads\/sites\/23\/2023\/09\/04.09_JBC_LIDE-dee-1024x576.jpg 1024w, https:\/\/goias.gov.br\/abc\/wp-content\/uploads\/sites\/23\/2023\/09\/04.09_JBC_LIDE-dee-768x432.jpg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/p>\n<p>Em sua palestra, o governador&nbsp;falou dos avan&ccedil;os da situa&ccedil;&atilde;o financeira do Estado, da transpar&ecirc;ncia de dados e das a&ccedil;&otilde;es na sa&uacute;de e na &aacute;rea social<\/p>\n<p><!--more--><\/p>\n<p>O governador Ronaldo Caiado participou, na &uacute;ltima sexta-feira (1&ordm;) em Washington, capital dos Estados Unidos, do <em>Lide Brazil Development<\/em>, um f&oacute;rum empresarial onde foram discutidas as oportunidades de investimentos em infraestrutura e tamb&eacute;m em servi&ccedil;os p&uacute;blicos nos Estados e munic&iacute;pios brasileiros. A apresenta&ccedil;&atilde;o do governador de Goi&aacute;s no evento foi mostrada em reportagem exibida no Jornal Brasil Central do &uacute;ltimo s&aacute;bado (2).<\/p>\n<p>O grupo de L&iacute;deres Empresariais (Lide) &eacute; uma organiza&ccedil;&atilde;o que re&uacute;ne executivos dos mais variados setores de atua&ccedil;&atilde;o em busca de fortalecer a livre iniciativa e o desenvolvimento econ&ocirc;mico e social, assim como a defesa dos princ&iacute;pios &eacute;ticos do governo nas esferas p&uacute;blica e privada.&nbsp;Na condi&ccedil;&atilde;o de convidado do f&oacute;rum, Ronaldo Caiado discursou sobre a situa&ccedil;&atilde;o em que assumiu o Estado de Goi&aacute;s e de como est&aacute; agora, sendo refer&ecirc;ncia em aspectos econ&ocirc;micos e sociais. Ele contou que, depois do Rio de Janeiro, Goi&aacute;s conseguiu entrar no Regime de Recupera&ccedil;&atilde;o Fiscal (RFF). &ldquo;A partir da&iacute;, n&oacute;s avan&ccedil;amos rapidamente na reorganiza&ccedil;&atilde;o do Estado. Tomamos todas as medidas que foram necess&aacute;rias.&rdquo;<\/p>\n<h2>Transpar&ecirc;ncia<\/h2>\n<p>Al&eacute;m dos l&iacute;deres governamentais, representantes de empresas brasileiras e multinacionais, que praticam governan&ccedil;a corporativa, valorizam o ser humano e respeitam o meio ambiente, ouviram do governador de Goi&aacute;s como a transpar&ecirc;ncia de dados auxiliou na recupera&ccedil;&atilde;o do Estado, bem como a escolha de uma equipe de secret&aacute;rios de perfil t&eacute;cnico. &nbsp;Ele &nbsp;declarou que a informa&ccedil;&atilde;o e o compliance p&uacute;blico foram instalados em todos os &oacute;rg&atilde;os do Governo. &ldquo;Neste momento, n&oacute;s vimos realmente o Estado tomar um outro rumo&rdquo;, afirmou.<\/p>\n<p>Caiado ainda falou sobre a situa&ccedil;&atilde;o da sa&uacute;de em Goi&aacute;s. O governador ressaltou que no Estado existiam apenas UTIs em um raio de dist&acirc;ncia de apenas 50 quil&ocirc;metros da capital, cen&aacute;rio que mudou desde o in&iacute;cio do processo de regionaliza&ccedil;&atilde;o da sa&uacute;de, onde agora h&aacute; um atendimento mais r&aacute;pido para os pacientes de cidades do interior. A&ccedil;&otilde;es sociais desenvolvidas pela primeira-dama Gracinha Caiado tamb&eacute;m foram pauta da apresenta&ccedil;&atilde;o. &ldquo;Foi algo que trouxe um grande resultado para o Estado de Goi&aacute;s&rdquo;, completou.<\/p>\n<p><strong>ABC Digital<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em sua palestra, o governador&nbsp;falou dos avan&ccedil;os da situa&ccedil;&atilde;o financeira do Estado, da transpar&ecirc;ncia de dados e das a&ccedil;&otilde;es na sa&uacute;de e na &aacute;rea social<\/p>\n","protected":false},"author":247,"featured_media":20730,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[39],"tags":[],"class_list":["post-20731","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"rttpg_featured_image_url":{"full":["https:\/\/goias.gov.br\/abc\/wp-content\/uploads\/sites\/23\/2023\/09\/04.09_JBC_LIDE-dee.jpg",1280,720,false],"landscape":["https:\/\/goias.gov.br\/abc\/wp-content\/uploads\/sites\/23\/2023\/09\/04.09_JBC_LIDE-dee.jpg",1280,720,false],"portraits":["https:\/\/goias.gov.br\/abc\/wp-content\/uploads\/sites\/23\/2023\/09\/04.09_JBC_LIDE-dee.jpg",1280,720,false],"thumbnail":["https:\/\/goias.gov.br\/abc\/wp-content\/uploads\/sites\/23\/2023\/09\/04.09_JBC_LIDE-dee-150x150.jpg",150,150,true],"medium":["https:\/\/goias.gov.br\/abc\/wp-content\/uploads\/sites\/23\/2023\/09\/04.09_JBC_LIDE-dee-300x169.jpg",300,169,true],"large":["https:\/\/goias.gov.br\/abc\/wp-content\/uploads\/sites\/23\/2023\/09\/04.09_JBC_LIDE-dee-1024x576.jpg",1024,576,true],"1536x1536":["https:\/\/goias.gov.br\/abc\/wp-content\/uploads\/sites\/23\/2023\/09\/04.09_JBC_LIDE-dee.jpg",1280,720,false],"2048x2048":["https:\/\/goias.gov.br\/abc\/wp-content\/uploads\/sites\/23\/2023\/09\/04.09_JBC_LIDE-dee.jpg",1280,720,false]},"rttpg_author":{"display_name":"lucelialima","author_link":"https:\/\/goias.gov.br\/abc\/author\/lucelialima\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/abc\/categoria\/institucional\/noticias\/\" rel=\"category tag\">Not\u00edcias<\/a>","rttpg_excerpt":"Em sua palestra, o governador&nbsp;falou dos avan&ccedil;os da situa&ccedil;&atilde;o financeira do Estado, da transpar&ecirc;ncia de dados e das a&ccedil;&otilde;es na sa&uacute;de e na &aacute;rea social","_links":{"self":[{"href":"https:\/\/goias.gov.br\/abc\/wp-json\/wp\/v2\/posts\/20731","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/abc\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/abc\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/abc\/wp-json\/wp\/v2\/users\/247"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/abc\/wp-json\/wp\/v2\/comments?post=20731"}],"version-history":[{"count":0,"href":"https:\/\/goias.gov.br\/abc\/wp-json\/wp\/v2\/posts\/20731\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/abc\/wp-json\/wp\/v2\/media\/20730"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/abc\/wp-json\/wp\/v2\/media?parent=20731"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/abc\/wp-json\/wp\/v2\/categories?post=20731"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/abc\/wp-json\/wp\/v2\/tags?post=20731"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}