

{"id":20512,"date":"2023-08-03T10:55:55","date_gmt":"2023-08-03T13:55:55","guid":{"rendered":"https:\/\/siteshom.goias.gov.br\/abc\/novos-gestores-da-educacao-tomam-posse-em-anapolis\/"},"modified":"2023-08-03T10:55:55","modified_gmt":"2023-08-03T13:55:55","slug":"novos-gestores-da-educacao-tomam-posse-em-anapolis","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/abc\/novos-gestores-da-educacao-tomam-posse-em-anapolis\/","title":{"rendered":"Novos gestores da Educa\u00e7\u00e3o tomam posse em An\u00e1polis"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-20511\" src=\"https:\/\/goias.gov.br\/abc\/wp-content\/uploads\/sites\/23\/2023\/08\/03.08_OMESC_EDUCACAO-8f3.jpg\" alt=\"\" width=\"1280\" height=\"720\" srcset=\"https:\/\/goias.gov.br\/abc\/wp-content\/uploads\/sites\/23\/2023\/08\/03.08_OMESC_EDUCACAO-8f3.jpg 1280w, https:\/\/goias.gov.br\/abc\/wp-content\/uploads\/sites\/23\/2023\/08\/03.08_OMESC_EDUCACAO-8f3-300x169.jpg 300w, https:\/\/goias.gov.br\/abc\/wp-content\/uploads\/sites\/23\/2023\/08\/03.08_OMESC_EDUCACAO-8f3-1024x576.jpg 1024w, https:\/\/goias.gov.br\/abc\/wp-content\/uploads\/sites\/23\/2023\/08\/03.08_OMESC_EDUCACAO-8f3-768x432.jpg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/p>\n<p>Ao todo, 998 diretores,&nbsp;que estar&atilde;o &agrave; frente das escolas p&uacute;blicas at&eacute; 2025, assumiram a fun&ccedil;&atilde;o<\/p>\n<p><!--more--><\/p>\n<p>A solenidade de posse dos novos gestores das escolas p&uacute;blicas estaduais ocorreu na noite desta quarta-feira (2), no Centro de Conven&ccedil;&otilde;es de An&aacute;polis. Na ocasi&atilde;o, o governador Ronaldo Caiado assinou o termo de posse e destacou as melhorias e investimentos realizados na educa&ccedil;&atilde;o p&uacute;blica estadual nos &uacute;ltimos quatro anos e meio. Reportagem veiculada no <em>O Mundo em Sua Casa<\/em> desta quinta-feira (3) destacou o m&eacute;todo de sele&ccedil;&atilde;o dos gestores. Conforme determina&ccedil;&atilde;o de Caiado, a escolha &eacute; realizada por meio de um processo democr&aacute;tico e aberto a toda a comunidade escolar. Todos os escolhidos s&atilde;o servidores efetivos da rede.<\/p>\n<p>O Estado possui 998 unidades a atende 476 mil estudantes nos Ensinos Fundamental, M&eacute;dio e na Educa&ccedil;&atilde;o de Jovens e Adultos (EJA). Os profissionais eleitos v&atilde;o gerir as unidades regulares e militares durante o bi&ecirc;nio 2023\/25 nos 246 munic&iacute;pios goianos. O governador Ronaldo Caiado reafirmou o compromisso da gest&atilde;o s&eacute;ria, sem apadrinhamentos pol&iacute;ticos. &ldquo;Todos aqui foram submetidos a um concurso p&uacute;blico e, aqueles que conseguiram aprova&ccedil;&atilde;o, foram empossados na condi&ccedil;&atilde;o de diretores&rdquo;, contou.<\/p>\n<p>Para a secret&aacute;ria de Estado da Educa&ccedil;&atilde;o, F&aacute;tima Gavioli, o momento &eacute; de comemorar os resultados alcan&ccedil;ados em Goi&aacute;s. &ldquo;O Brasil discute muito a forma&ccedil;&atilde;o continuada, mas &eacute; preciso uma forma&ccedil;&atilde;o inicial que diz: a sua tarefa &eacute; essa, o seu dever &eacute; esse, o seu compromisso com a rede &eacute; esse. E, principalmente, conhecer os direitos e deveres no exerc&iacute;cio da fun&ccedil;&atilde;o&rdquo;, explicou.<\/p>\n<p>A solenidade de posse integrou a programa&ccedil;&atilde;o do primeiro Encontro Estadual de Gestores da Educa&ccedil;&atilde;o de 2023, que termina nesta quinta-feira (3). Durante o evento, professores, diretores e servidores administrativos s&atilde;o convidados a planejar a&ccedil;&otilde;es na &aacute;rea. Tamb&eacute;m s&atilde;o oferecidas palestras com especialistas. Ainda durante o evento, foi anunciada&nbsp;a entrega de 129 ve&iacute;culos para a Seduc, sendo 74 sedans, 54 caminhonetes e uma SUV.<\/p>\n<p><strong>ABC Digital<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ao todo, 998 diretores,&nbsp;que estar&atilde;o &agrave; frente das escolas p&uacute;blicas at&eacute; 2025, assumiram a fun&ccedil;&atilde;o<\/p>\n","protected":false},"author":252,"featured_media":20511,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[39],"tags":[],"class_list":["post-20512","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"rttpg_featured_image_url":{"full":["https:\/\/goias.gov.br\/abc\/wp-content\/uploads\/sites\/23\/2023\/08\/03.08_OMESC_EDUCACAO-8f3.jpg",1280,720,false],"landscape":["https:\/\/goias.gov.br\/abc\/wp-content\/uploads\/sites\/23\/2023\/08\/03.08_OMESC_EDUCACAO-8f3.jpg",1280,720,false],"portraits":["https:\/\/goias.gov.br\/abc\/wp-content\/uploads\/sites\/23\/2023\/08\/03.08_OMESC_EDUCACAO-8f3.jpg",1280,720,false],"thumbnail":["https:\/\/goias.gov.br\/abc\/wp-content\/uploads\/sites\/23\/2023\/08\/03.08_OMESC_EDUCACAO-8f3-150x150.jpg",150,150,true],"medium":["https:\/\/goias.gov.br\/abc\/wp-content\/uploads\/sites\/23\/2023\/08\/03.08_OMESC_EDUCACAO-8f3-300x169.jpg",300,169,true],"large":["https:\/\/goias.gov.br\/abc\/wp-content\/uploads\/sites\/23\/2023\/08\/03.08_OMESC_EDUCACAO-8f3-1024x576.jpg",1024,576,true],"1536x1536":["https:\/\/goias.gov.br\/abc\/wp-content\/uploads\/sites\/23\/2023\/08\/03.08_OMESC_EDUCACAO-8f3.jpg",1280,720,false],"2048x2048":["https:\/\/goias.gov.br\/abc\/wp-content\/uploads\/sites\/23\/2023\/08\/03.08_OMESC_EDUCACAO-8f3.jpg",1280,720,false]},"rttpg_author":{"display_name":"brunassantos","author_link":"https:\/\/goias.gov.br\/abc\/author\/brunassantos\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/abc\/categoria\/institucional\/noticias\/\" rel=\"category tag\">Not\u00edcias<\/a>","rttpg_excerpt":"Ao todo, 998 diretores,&nbsp;que estar&atilde;o &agrave; frente das escolas p&uacute;blicas at&eacute; 2025, assumiram a fun&ccedil;&atilde;o","_links":{"self":[{"href":"https:\/\/goias.gov.br\/abc\/wp-json\/wp\/v2\/posts\/20512","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/abc\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/abc\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/abc\/wp-json\/wp\/v2\/users\/252"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/abc\/wp-json\/wp\/v2\/comments?post=20512"}],"version-history":[{"count":0,"href":"https:\/\/goias.gov.br\/abc\/wp-json\/wp\/v2\/posts\/20512\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/abc\/wp-json\/wp\/v2\/media\/20511"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/abc\/wp-json\/wp\/v2\/media?parent=20512"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/abc\/wp-json\/wp\/v2\/categories?post=20512"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/abc\/wp-json\/wp\/v2\/tags?post=20512"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}