

{"id":17767,"date":"2021-12-27T15:58:08","date_gmt":"2021-12-27T18:58:08","guid":{"rendered":"https:\/\/siteshom.goias.gov.br\/abc\/brasil-central-apresenta-sua-retrospectiva-2021-nesta-terca-feira\/"},"modified":"2021-12-27T15:58:08","modified_gmt":"2021-12-27T18:58:08","slug":"brasil-central-apresenta-sua-retrospectiva-2021-nesta-terca-feira","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/abc\/brasil-central-apresenta-sua-retrospectiva-2021-nesta-terca-feira\/","title":{"rendered":"Brasil Central apresenta sua retrospectiva 2021 nesta ter\u00e7a-feira"},"content":{"rendered":"<p>Programa vai ao ar &agrave;s 14 horas e ser&aacute; reapresentado &agrave;s 22 horas. Al&eacute;m disso, telespectador ter&aacute; oportunidade de ver o conte&uacute;do na quarta e quinta-feira, nos mesmos hor&aacute;rios<\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: center;\"><iframe allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen=\"\" frameborder=\"0\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/JaJrIcVGyOQ\" title=\"YouTube video player\" width=\"560\"><\/iframe><\/p>\n<p>Um amplo balan&ccedil;o com as principais a&ccedil;&otilde;es e realiza&ccedil;&otilde;es da Ag&ecirc;ncia Brasil Central em 2021 ser&aacute; levado ao ar nesta ter&ccedil;a-feira, 28, a partir das 14 horas. Trata-se da retrospectiva que recebeu o nome de 2021: o Ano da Brasil Central, produzida ao longo deste m&ecirc;s com participa&ccedil;&atilde;o de dirigentes e coordenadores de todos os setores da ABC. O programa tamb&eacute;m ser&aacute; exibido &agrave;s 22h desta ter&ccedil;a&nbsp;e ainda &agrave;s 14h e 22h de&nbsp;quarta e quinta, 29&nbsp;e 30.<\/p>\n<p>O objetivo, conforme destaca o presidente da Ag&ecirc;ncia, Reginaldo J&uacute;nior, &eacute; mostrar aos diversos p&uacute;blicos os avan&ccedil;os implementados nas &aacute;reas administrativas e as inova&ccedil;&otilde;es ocorridas nos processos de produ&ccedil;&atilde;o e veicula&ccedil;&atilde;o de conte&uacute;dos informativos, em especial quanto ao substancial aumento da produ&ccedil;&atilde;o pr&oacute;pria nas &aacute;reas de jornalismo, cultura e esportes.<\/p>\n<p>O programa ter&aacute; uma hora de dura&ccedil;&atilde;o e focaliza de forma abrangente todas as &aacute;reas da Ag&ecirc;ncia, enfatizando as principais a&ccedil;&otilde;es e realiza&ccedil;&otilde;es. Um dos destaques &eacute; o depoimento do presidente Reginaldo J&uacute;nior, que ir&aacute; mostrar todos os avan&ccedil;os da gest&atilde;o, moderniza&ccedil;&atilde;o dos processos administrativos e mudan&ccedil;as nas &aacute;reas fins, voltadas &agrave; divulga&ccedil;&atilde;o institucional e oficial das atividades do Governo de Goi&aacute;s, bem como not&iacute;cias dos principais fatos e acontecimentos ocorridos no Estado.<\/p>\n<h2>Integra&ccedil;&atilde;o de m&iacute;dias<\/h2>\n<p>Um dos principais pontos a serem destacados est&aacute; relacionado ao esfor&ccedil;o da administra&ccedil;&atilde;o na implementa&ccedil;&atilde;o de tecnologias que impulsionaram e consolidaram a integra&ccedil;&atilde;o da TV Brasil Central com as r&aacute;dios Brasil Central AM e RBC FM, e ainda com as m&iacute;dias digitais, disponibilizando informa&ccedil;&otilde;es para os diversos p&uacute;blicos. Vale destacar a veicula&ccedil;&atilde;o em tempo real dos programas em m&iacute;dias como YouTube e Facebook, o que significa a universaliza&ccedil;&atilde;o dos conte&uacute;dos. E ainda o uso intensivo de ferramentas como Instagram, Twitter, podcast e outras.<\/p>\n<p>A produ&ccedil;&atilde;o da retrospectiva envolve diversos profissionais das equipes de TV, R&aacute;dio e ABC Digital. Confira a ficha t&eacute;cnica da retrospectiva:<\/p>\n<p>Coordena&ccedil;&atilde;o Geral: &nbsp;Maz&eacute; Alves<br \/>\nDire&ccedil;&atilde;o: C&eacute;lio Silveira<br \/>\nCoordena&ccedil;&atilde;o, reda&ccedil;&atilde;o e apresenta&ccedil;&atilde;o: Gra&ccedil;a Torres<br \/>\nProdu&ccedil;&atilde;o: Ana L&uacute;cia<br \/>\nMaquiagem: Concei&ccedil;&atilde;o Ferreira, Bruna Castro, Thais Dwcki,&nbsp;Ceissa Makeup<br \/>\nProdu&ccedil;&atilde;o Jornalismo: D&eacute;bora Moraes<br \/>\nChefia de reportagem : D&eacute;bora Moraes, Ione Chagas, Jer&ocirc;nimo Ven&acirc;ncio, Juliana Barcelos&nbsp;&nbsp; &nbsp;<br \/>\nRevis&atilde;o de texto final: Enzo de Lisita<br \/>\nCoordena&ccedil;&atilde;o de Edi&ccedil;&atilde;o: &nbsp;Norma Leitte<br \/>\nEdi&ccedil;&atilde;o: Daniel Dutra, Miguelangelo Carvalho, Rafael Rezende, Elessandro Santana<br \/>\nEdi&ccedil;&atilde;o e finaliza&ccedil;&atilde;o:&nbsp;Bruna Chamelet, Daniel Dutra<br \/>\nImagens de Apoio: Thiago Costa<br \/>\nVideografista : Paulo Caetano,&nbsp;Kanji Yamamoto<br \/>\nCen&aacute;rio virtual: C&eacute;lio Silveira, Paulo Caetano<br \/>\nCoordena&ccedil;&atilde;o da ABC Digital: Marcela Freitas&nbsp;<br \/>\nCoordena&ccedil;&atilde;o do Departamento de Conte&uacute;do: Maz&eacute; Alves<br \/>\nCoordena&ccedil;&atilde;o de telejornalismo: Eva Taucci&nbsp;<br \/>\nCoordena&ccedil;&atilde;o de integra&ccedil;&atilde;o RTV: Francielly Oliveira<br \/>\nGer&ecirc;ncia de TV: Daniel Santana<br \/>\nDire&ccedil;&atilde;o de Telerradiodifus&atilde;o: Rafael Vasconcelos<br \/>\nPresid&ecirc;ncia: Reginaldo Junior<\/p>\n<p><strong>ABC Digital<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Programa vai ao ar &agrave;s 14 horas e ser&aacute; reapresentado &agrave;s 22 horas. Al&eacute;m disso, telespectador ter&aacute; oportunidade de ver o conte&uacute;do na quarta e quinta-feira, nos mesmos hor&aacute;rios<\/p>\n","protected":false},"author":7,"featured_media":17731,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[39],"tags":[],"class_list":["post-17767","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"rttpg_featured_image_url":{"full":["https:\/\/goias.gov.br\/abc\/wp-content\/uploads\/sites\/23\/2021\/12\/0912_ABC_RETROSPECTIVA-2af.png",1280,720,false],"landscape":["https:\/\/goias.gov.br\/abc\/wp-content\/uploads\/sites\/23\/2021\/12\/0912_ABC_RETROSPECTIVA-2af.png",1280,720,false],"portraits":["https:\/\/goias.gov.br\/abc\/wp-content\/uploads\/sites\/23\/2021\/12\/0912_ABC_RETROSPECTIVA-2af.png",1280,720,false],"thumbnail":["https:\/\/goias.gov.br\/abc\/wp-content\/uploads\/sites\/23\/2021\/12\/0912_ABC_RETROSPECTIVA-2af-150x150.png",150,150,true],"medium":["https:\/\/goias.gov.br\/abc\/wp-content\/uploads\/sites\/23\/2021\/12\/0912_ABC_RETROSPECTIVA-2af-300x169.png",300,169,true],"large":["https:\/\/goias.gov.br\/abc\/wp-content\/uploads\/sites\/23\/2021\/12\/0912_ABC_RETROSPECTIVA-2af-1024x576.png",1024,576,true],"1536x1536":["https:\/\/goias.gov.br\/abc\/wp-content\/uploads\/sites\/23\/2021\/12\/0912_ABC_RETROSPECTIVA-2af.png",1280,720,false],"2048x2048":["https:\/\/goias.gov.br\/abc\/wp-content\/uploads\/sites\/23\/2021\/12\/0912_ABC_RETROSPECTIVA-2af.png",1280,720,false]},"rttpg_author":{"display_name":"gustavogoncalves","author_link":"https:\/\/goias.gov.br\/abc\/author\/gustavogoncalves\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/abc\/categoria\/institucional\/noticias\/\" rel=\"category tag\">Not\u00edcias<\/a>","rttpg_excerpt":"Programa vai ao ar &agrave;s 14 horas e ser&aacute; reapresentado &agrave;s 22 horas. Al&eacute;m disso, telespectador ter&aacute; oportunidade de ver o conte&uacute;do na quarta e quinta-feira, nos mesmos hor&aacute;rios","_links":{"self":[{"href":"https:\/\/goias.gov.br\/abc\/wp-json\/wp\/v2\/posts\/17767","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/abc\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/abc\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/abc\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/abc\/wp-json\/wp\/v2\/comments?post=17767"}],"version-history":[{"count":0,"href":"https:\/\/goias.gov.br\/abc\/wp-json\/wp\/v2\/posts\/17767\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/abc\/wp-json\/wp\/v2\/media\/17731"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/abc\/wp-json\/wp\/v2\/media?parent=17767"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/abc\/wp-json\/wp\/v2\/categories?post=17767"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/abc\/wp-json\/wp\/v2\/tags?post=17767"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}