

{"id":108572,"date":"2025-10-08T09:00:00","date_gmt":"2025-10-08T12:00:00","guid":{"rendered":"https:\/\/goias.gov.br\/abc\/?p=108572"},"modified":"2025-10-08T09:44:37","modified_gmt":"2025-10-08T12:44:37","slug":"ses-lanca-pesquisa-de-satisfacao-das-unidades-de-saude","status":"publish","type":"post","link":"https:\/\/goias.gov.br\/abc\/ses-lanca-pesquisa-de-satisfacao-das-unidades-de-saude\/","title":{"rendered":"SES lan\u00e7a pesquisa de satisfa\u00e7\u00e3o das unidades de sa\u00fade"},"content":{"rendered":"\n<p>A Secretaria de Estado da Sa\u00fade (SES), em parceria com o Tribunal de Contas (TCE) e a Controladoria Geral (CGE-GO), lan\u00e7ou nesta ter\u00e7a-feira (7), em Goi\u00e2nia, a <em>Pesquisa de Satisfa\u00e7\u00e3o das Unidades de Sa\u00fade do Estado de Goi\u00e1s<\/em>. A iniciativa tem como objetivo dar mais transpar\u00eancia e qualidade aos atendimentos prestados no Sistema \u00danico de Sa\u00fade (SES). Com isso, o cidad\u00e3o goiano passa a ser ouvido com mais aten\u00e7\u00e3o e participa ativamente da avalia\u00e7\u00e3o da qualidade dos servi\u00e7os prestados na \u00e1rea da sa\u00fade.<\/p>\n\n\n\n<p>Em entrevista \u00e0 TV Brasil Central, o secret\u00e1rio de Estado da Sa\u00fade, Ras\u00edvel dos Santos, afirmou: \u201c\u00c9 muito importante que a gente tenha esse tipo de pesquisa, para que eles avaliem toda a infraestrutura, a qualidade da assist\u00eancia, como foi o atendimento m\u00e9dico, o tempo de espera, ent\u00e3o tudo os que os usu\u00e1rios consideram como valor, que eles possam avaliar\u201d. A avalia\u00e7\u00e3o ser\u00e1 realizada atrav\u00e9s de um QR Code que ser\u00e1 disponibilizado nos 32 hospitais da SES.<\/p>\n\n\n\n<p>O secret\u00e1rio chefe da CGE-GO, Marcos Tadeu, ressaltou que \u00e9 importante saber o quer o usu\u00e1rio pensa do hospital, qual foi a experi\u00eancia que ele teve, al\u00e9m de poder fazer a avalia\u00e7\u00e3o das equipes que o atenderam e da estrutura da unidade de sa\u00fade. Acrescentou que a iniciativa contribui com a possibilidade de melhoria dos servi\u00e7os de sa\u00fade prestados pelos hospitais estaduais.<\/p>\n\n\n\n<p><strong>ABC Digital<\/strong><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Secretaria de Estado da Sa\u00fade (SES), em parceria com o Tribunal de Contas (TCE) e a Controladoria Geral (CGE-GO), lan\u00e7ou nesta ter\u00e7a-feira (7), em Goi\u00e2nia, a Pesquisa de Satisfa\u00e7\u00e3o das Unidades de Sa\u00fade do Estado de Goi\u00e1s. A iniciativa tem como objetivo dar mais transpar\u00eancia e qualidade aos atendimentos prestados no Sistema \u00danico de [&hellip;]<\/p>\n","protected":false},"author":379,"featured_media":108557,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[39],"tags":[58],"class_list":["post-108572","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-jornalismo"],"rttpg_featured_image_url":{"full":["https:\/\/goias.gov.br\/abc\/wp-content\/uploads\/sites\/23\/2025\/10\/2025.10.08_TBCN_SAUDE.jpg",1200,600,false],"landscape":["https:\/\/goias.gov.br\/abc\/wp-content\/uploads\/sites\/23\/2025\/10\/2025.10.08_TBCN_SAUDE.jpg",1200,600,false],"portraits":["https:\/\/goias.gov.br\/abc\/wp-content\/uploads\/sites\/23\/2025\/10\/2025.10.08_TBCN_SAUDE.jpg",1200,600,false],"thumbnail":["https:\/\/goias.gov.br\/abc\/wp-content\/uploads\/sites\/23\/2025\/10\/2025.10.08_TBCN_SAUDE-150x150.jpg",150,150,true],"medium":["https:\/\/goias.gov.br\/abc\/wp-content\/uploads\/sites\/23\/2025\/10\/2025.10.08_TBCN_SAUDE-300x150.jpg",300,150,true],"large":["https:\/\/goias.gov.br\/abc\/wp-content\/uploads\/sites\/23\/2025\/10\/2025.10.08_TBCN_SAUDE-1024x512.jpg",1024,512,true],"1536x1536":["https:\/\/goias.gov.br\/abc\/wp-content\/uploads\/sites\/23\/2025\/10\/2025.10.08_TBCN_SAUDE.jpg",1200,600,false],"2048x2048":["https:\/\/goias.gov.br\/abc\/wp-content\/uploads\/sites\/23\/2025\/10\/2025.10.08_TBCN_SAUDE.jpg",1200,600,false]},"rttpg_author":{"display_name":"marizasantana","author_link":"https:\/\/goias.gov.br\/abc\/author\/marizasantana\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/goias.gov.br\/abc\/categoria\/institucional\/noticias\/\" rel=\"category tag\">Not\u00edcias<\/a>","rttpg_excerpt":"A Secretaria de Estado da Sa\u00fade (SES), em parceria com o Tribunal de Contas (TCE) e a Controladoria Geral (CGE-GO), lan\u00e7ou nesta ter\u00e7a-feira (7), em Goi\u00e2nia, a Pesquisa de Satisfa\u00e7\u00e3o das Unidades de Sa\u00fade do Estado de Goi\u00e1s. A iniciativa tem como objetivo dar mais transpar\u00eancia e qualidade aos atendimentos prestados no Sistema \u00danico de&hellip;","_links":{"self":[{"href":"https:\/\/goias.gov.br\/abc\/wp-json\/wp\/v2\/posts\/108572","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goias.gov.br\/abc\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goias.gov.br\/abc\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/abc\/wp-json\/wp\/v2\/users\/379"}],"replies":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/abc\/wp-json\/wp\/v2\/comments?post=108572"}],"version-history":[{"count":2,"href":"https:\/\/goias.gov.br\/abc\/wp-json\/wp\/v2\/posts\/108572\/revisions"}],"predecessor-version":[{"id":108605,"href":"https:\/\/goias.gov.br\/abc\/wp-json\/wp\/v2\/posts\/108572\/revisions\/108605"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/goias.gov.br\/abc\/wp-json\/wp\/v2\/media\/108557"}],"wp:attachment":[{"href":"https:\/\/goias.gov.br\/abc\/wp-json\/wp\/v2\/media?parent=108572"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goias.gov.br\/abc\/wp-json\/wp\/v2\/categories?post=108572"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goias.gov.br\/abc\/wp-json\/wp\/v2\/tags?post=108572"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}